{"id":917,"date":"2020-07-22T09:08:31","date_gmt":"2020-07-22T07:08:31","guid":{"rendered":"http:\/\/viennatouristinformation.com\/es\/?page_id=917"},"modified":"2023-06-14T14:29:38","modified_gmt":"2023-06-14T12:29:38","slug":"zoologico-de-schoenbrunn","status":"publish","type":"page","link":"https:\/\/viennatouristinformation.com\/es\/cosas-que-hacer\/atracciones\/zoologico-de-schoenbrunn\/","title":{"rendered":"Zool\u00f3gico de Sch\u00f6nbrunn Viena: Animales, visitas y consejos de viaje"},"content":{"rendered":"<h2 id=\"t-1669899315257\" data-hide=\"true\">El zool\u00f3gico de Sch\u00f6nbrunn en el parque del palacio, en los terrenos del famoso Palacio de <a href=\"https:\/\/viennatouristinformation.com\/es\/cosas-que-hacer\/castillos\/schoenbrunn\/\" style=\"outline: none;\">Sch\u00f6nbrunn<\/a> , es el zool\u00f3gico m\u00e1s antiguo del mundo.<\/h2>\n<p>Fue fundado en 1752 por el emperador Francisco I Esteban de Lorena, esposo de Mar\u00eda Teresa.<\/p>\n<p>No solo es parte del Patrimonio de la Humanidad de la UNESCO de Sch\u00f6nbrunn, sino que tambi\u00e9n ha sido nombrado \u00abMejor zool\u00f3gico de Europa\u00bb cinco veces seguidas.<\/p>\n<p>Con m\u00e1s de 2 millones de visitantes al a\u00f1o, el zool\u00f3gico es una <a href=\"https:\/\/viennatouristinformation.com\/es\/cosas-que-hacer\/\" style=\"outline: none;\">de las atracciones m\u00e1s visitadas de Viena<\/a> .<\/p>\n<p style=\"\"><strong>Otros art\u00edculos recomendados:<\/strong><\/p>\n<ul>\n<li><a href=\"https:\/\/viennatouristinformation.com\/es\/cosas-que-hacer\/10-mejores\/\" style=\"outline: none;\">Las 10 mejores cosas que hacer en Viena<\/a><\/li>\n<li><a href=\"https:\/\/viennatouristinformation.com\/es\/hoteles\/\" style=\"outline: none;\">Los hoteles mejor recomendados en Viena<\/a><\/li>\n<li><a href=\"https:\/\/viennatouristinformation.com\/es\/cosas-que-hacer\/atracciones\/\">Atracciones excepcionales en Viena<\/a><\/li>\n<li><a href=\"https:\/\/viennatouristinformation.com\/es\/comida\/\">Los mejores restaurantes de Viena<\/a><\/li>\n<li><a href=\"https:\/\/viennatouristinformation.com\/es\/compras\/\">Compras en Viena<\/a><\/li>\n<li><a href=\"https:\/\/viennatouristinformation.com\/es\/plan\/transporte-publico\/\">Transporte p\u00fablico en Viena<\/a><\/li>\n<\/ul>\n<h2 id=\"t-1669899315258\" style=\"\">\u00bfQu\u00e9 animales puedo ver en el zool\u00f3gico de Sch\u00f6nbrunn?<\/h2>\n<p><span><img decoding=\"async\" alt=\"Welche Tiere kann ich im Tiergarten Sch\u00f6nbrunn sehen\" data-id=\"1955\" width=\"885\" data-init-width=\"1000\" height=\"590\" data-init-height=\"667\" title=\"Welche Tiere kann ich im Tiergarten Sch\u00f6nbrunn sehen\" loading=\"lazy\" src=\"\/\/viennatouristinformation.com\/es\/wp-content\/uploads\/2020\/09\/Welche-Tiere-kann-ich-im-Tiergarten-Sch\u00f6nbrunn-sehen.jpg\" data-width=\"885\" data-height=\"590\" data-pin-media=\"https:\/\/viennatouristinformation.com\/es\/wp-content\/uploads\/2021\/01\/wien_pinterest_tiergarten-2.jpg\" data-pin-description=\"Zool\u00f3gico de Sch\u00f6nbrunn Viena: animales, visitas y consejos de viaje\" data-pin-url=\"https:\/\/viennatouristinformation.com\/es\/cosas-que-hacer\/atracciones\/zoologico-de-schoenbrunn\/?tve=true&amp;tcbf=d5716ea3f9\" data-pinpro-key=\"q17w4csuk\" style=\"aspect-ratio: auto 1000 \/ 667;\"><\/span><\/p>\n<p>M\u00e1s de 750 especies de animales y 8.000 animales llaman hogar al zool\u00f3gico de Sch\u00f6nbrunn.<\/p>\n<p>Aqu\u00ed hay una peque\u00f1a selecci\u00f3n:<\/p>\n<ul>\n<li><strong>Osos polares:<\/strong> los gigantes blancos le dan la bienvenida al mundo de los osos polares de 1.700 m\u00b2 \u00abFranz Josef Land\u00bb. La osa polar reci\u00e9n nacida Finja, que se ha ganado los corazones de los visitantes desde que naci\u00f3 en noviembre de 2019, es particularmente popular.<\/li>\n<li><strong>Pandas:<\/strong> Los pandas, uno de los mam\u00edferos m\u00e1s raros del mundo, atraen multitudes.<\/li>\n<li><strong>Elefantes<\/strong> : Los elefantes africanos tambi\u00e9n son muy populares. Desde julio de 2019, la ni\u00f1a elefante Kibali ha deleitado a todos.<\/li>\n<li>Leones: en el zool\u00f3gico de Sch\u00f6nbrunn, tambi\u00e9n puede maravillarse con los poderosos leones que deambulan por su territorio.<\/li>\n<li><strong>Orangutanes:<\/strong> En ORANG.erie, los visitantes pueden ver orangutanes haciendo gimnasia, columpi\u00e1ndose y relaj\u00e1ndose. Adem\u00e1s del recinto al aire libre, ORANG.erie tambi\u00e9n posee el <em>Caf\u00e9 Atelier Nonja<\/em> con una vista directa de los grandes simios.<\/li>\n<li><strong>Casa de los monos:<\/strong> La casa de los monos es el hogar de seis especies de monos: colobo, l\u00e9mur rufo rojo, tit\u00ed pigmeo, tit\u00ed emperador y tit\u00ed, y monos ardilla. Suricatas tambi\u00e9n viven en el complejo.<\/li>\n<li><strong>Casa acuario y terrario:<\/strong> Este entorno alberga el <em>pabell\u00f3n<\/em> de cocodrilos con cocodrilos, tortugas y serpientes antenas, la casa <em>acuario<\/em> con una amplia gama de especies de peces, incluidas especies de peces en peligro de extinci\u00f3n, pira\u00f1as y arapaimas gigantes, as\u00ed como la <em>casa terrario<\/em> con numerosos reptiles como como iguanas rinoceronte, una gran anaconda, cobras, serpientes de cascabel y muchos m\u00e1s.<\/li>\n<li><strong>Jirafas:<\/strong> Las dos jirafas \u00abadolescentes\u00bb Fleur y Sofie, las residentes del parque de jirafas, tambi\u00e9n est\u00e1n muy entusiasmadas.<\/li>\n<li><strong>Rinocerontes:<\/strong> el parque de rinocerontes de 6.000 m\u00b2 no solo est\u00e1 habitado por rinocerontes indios, sino que tambi\u00e9n viven aqu\u00ed otras especies asi\u00e1ticas como ant\u00edlopes nilgai, ciervos sika vietnamitas y ant\u00edlopes negros.<\/li>\n<li><strong>Polarium<\/strong> : En el Polarium se pueden admirar focas de crin, ping\u00fcinos de penacho amarillo y ping\u00fcinos rey a trav\u00e9s del vaso de la piscina de 13 metros de largo <strong>.<\/strong><\/li>\n<li><strong>Rainforest<\/strong> House: esta enorme casa de cristal ocupa parte de la ladera de una monta\u00f1a en la selva tropical del sudeste asi\u00e1tico. Adem\u00e1s de la variedad de plantas, tambi\u00e9n hay numerosas especies animales, como nutrias pigmeas, tortugas de r\u00edo, pitones tigre, iguanas de Fiji y murci\u00e9lagos de hoja de anteojos. Gracias a la tecnolog\u00eda y los efectos especiales, como tormentas el\u00e9ctricas, bocanadas de niebla y temperaturas tropicales, los visitantes pueden esperar una experiencia aut\u00e9ntica.<\/li>\n<li><strong>South America Park:<\/strong> este h\u00e1bitat, modelado agr\u00edcolamente a partir de una pampa, alberga osos hormigueros gigantes, capibaras, tapires, vicu\u00f1as, seriemas y \u00f1and\u00faes.&nbsp; &nbsp;<\/li>\n<li><strong>Casa de \u00c1frica Oriental:<\/strong> aqu\u00ed retozan tokos, mangostas pigmeas y c\u00e1laos terrestres.<\/li>\n<li><strong>Sendero<\/strong> de descubrimiento de la naturaleza : Una atracci\u00f3n popular es el sendero de descubrimiento de la naturaleza que consta de tres etapas. Aqu\u00ed los visitantes pueden conocer mejor la flora y fauna local. Lo m\u00e1s destacado es el sendero de las copas de los \u00e1rboles de 160 metros de largo, donde puede pasear por un puente colgante de 10 metros de altura a trav\u00e9s de las copas de los \u00e1rboles de los bosques de Viena y disfrutar de maravillosas vistas del Palacio de <a href=\"https:\/\/viennatouristinformation.com\/es\/cosas-que-hacer\/castillos\/schoenbrunn\/\" style=\"outline: none;\">Sch\u00f6nbrunn .<\/a><\/li>\n<\/ul>\n<h2 id=\"t-1669899315259\" style=\"\">Precios: Entrada, entrada y pase anual<\/h2>\n<p><span><img decoding=\"async\" alt=\"Preise Eintritt, Ticket und Jahreskarte\" data-id=\"1956\" width=\"885\" data-init-width=\"1000\" height=\"590\" data-init-height=\"667\" title=\"Preise Eintritt, Ticket und Jahreskarte\" loading=\"lazy\" src=\"\/\/viennatouristinformation.com\/es\/wp-content\/uploads\/2020\/09\/Preise-Eintritt-Ticket-und-Jahreskarte.jpg\" data-width=\"885\" data-height=\"590\" data-pin-media=\"https:\/\/viennatouristinformation.com\/es\/wp-content\/uploads\/2021\/01\/wien_pinterest_tiergarten-2.jpg\" data-pin-description=\"Zool\u00f3gico de Sch\u00f6nbrunn Viena: animales, visitas y consejos de viaje\" data-pin-url=\"https:\/\/viennatouristinformation.com\/es\/cosas-que-hacer\/atracciones\/zoologico-de-schoenbrunn\/?tve=true&amp;tcbf=d5716ea3f9\" data-pinpro-key=\"dwiy92a4v\" style=\"aspect-ratio: auto 1000 \/ 667;\"><\/span><\/p>\n<ul>\n<li><strong>Entradas:<\/strong> Adultos pagan 22\u20ac por entrada de d\u00eda, ni\u00f1os y j\u00f3venes pagan 11\u20ac.<\/li>\n<li><strong>Entradas combinadas:<\/strong> el zool\u00f3gico de Sch\u00f6nbrunn ofrece varias entradas combinadas que los visitantes pueden usar para ahorrar. Puede encontrar una descripci\u00f3n general de todos los boletos combinados <a href=\"https:\/\/www.zoovienna.at\/besuch-und-tickets\/kombitickets\/\" rel=\"noopener\" target=\"_blank\">aqu\u00ed<\/a> .<\/li>\n<li><strong>Paquete ventaja:<\/strong> Existe un paquete ventaja por 65\u20ac, que consiste en entradas de 2 d\u00edas para adultos y entradas de 3 d\u00edas para ni\u00f1os\/adolescentes.<\/li>\n<li><strong>Visitas guiadas:<\/strong> Diversas visitas guiadas hacen de la visita una experiencia especial. Los horarios y precios actuales se pueden encontrar en la p\u00e1gina de <a href=\"https:\/\/www.zoovienna.at\/termine\/\" rel=\"noopener\" target=\"_blank\">inicio<\/a> del zool\u00f3gico .<\/li>\n<li><strong>Alimentaci\u00f3n:<\/strong> Las fechas actuales de las diversas alimentaciones, que son muy populares, se pueden encontrar <a href=\"https:\/\/www.zoovienna.at\/termine\/fuetterungen\/\" rel=\"noopener\" target=\"_blank\">aqu\u00ed<\/a> .<\/li>\n<li><strong>Pase anual :<\/strong> El zool\u00f3gico tambi\u00e9n ofrece un pase anual y es v\u00e1lido por un a\u00f1o a partir de la fecha de compra.<\/li>\n<\/ul>\n<h2 id=\"t-1669899315260\" style=\"\">Descuentos y vales<\/h2>\n<p><span><img decoding=\"async\" alt=\"Erm\u00e4\u00dfigungen und Gutscheine\" data-id=\"1957\" width=\"885\" data-init-width=\"1000\" height=\"590\" data-init-height=\"667\" title=\"Erm\u00e4\u00dfigungen und Gutscheine\" loading=\"lazy\" src=\"\/\/viennatouristinformation.com\/es\/wp-content\/uploads\/2020\/09\/Erm\u00e4\u00dfigungen-und-Gutscheine.jpg\" data-width=\"885\" data-height=\"590\" data-pin-media=\"https:\/\/viennatouristinformation.com\/es\/wp-content\/uploads\/2021\/01\/wien_pinterest_tiergarten-2.jpg\" data-pin-description=\"Zool\u00f3gico de Sch\u00f6nbrunn Viena: animales, visitas y consejos de viaje\" data-pin-url=\"https:\/\/viennatouristinformation.com\/es\/cosas-que-hacer\/atracciones\/zoologico-de-schoenbrunn\/?tve=true&amp;tcbf=d5716ea3f9\" data-pinpro-key=\"3s4q4yma1\" style=\"aspect-ratio: auto 1000 \/ 667;\"><\/span><\/p>\n<h3 id=\"t-1669899315261\" style=\"\"><strong>Descuentos:<\/strong><\/h3>\n<ul>\n<li>Los ni\u00f1os y j\u00f3venes de 6 a 18 a\u00f1os pagan 11 \u20ac.<\/li>\n<li>Los ni\u00f1os hasta los 6 a\u00f1os disfrutan de entrada gratuita.<\/li>\n<li>Los ni\u00f1os y j\u00f3venes con discapacidad (hasta los 19 a\u00f1os) reciben entrada gratuita, y un acompa\u00f1ante tambi\u00e9n recibe una entrada reducida.<\/li>\n<li>Las personas con un grado de discapacidad igual o superior al 50% obtienen una entrada reducida previa presentaci\u00f3n de la tarjeta de discapacidad.<\/li>\n<li>Las personas con un grado de discapacidad del 100% y 1 acompa\u00f1ante tienen entrada gratuita.<\/li>\n<li>Los titulares de la Vienna City Card reciben un 16 % de descuento sobre el precio de la entrada.<\/li>\n<\/ul>\n<h3 id=\"t-1669899315262\"><strong>Cupones:<\/strong><\/h3>\n<p>Tambi\u00e9n hay disponibles varios vales para el zool\u00f3gico. Todos los vales se pueden encontrar <a href=\"https:\/\/www.zoovienna.at\/shop\/kategorie\/Gutscheine\/\" rel=\"noopener\" target=\"_blank\">aqu\u00ed<\/a> .<\/p>\n<h2 id=\"t-1669899315263\" style=\"\">Lugares de inter\u00e9s en el Tiergarten<\/h2>\n<ul>\n<li><strong>Tirolerhof:<\/strong> disfrute del estilo tirol\u00e9s en Tirolerhof, una granja t\u00edpica de Unterinntal de 1722. Comprado en el zool\u00f3gico de Sch\u00f6nbrunn para salvarlo de la decadencia, removido y reconstruido aqu\u00ed pieza por pieza, el Tirolerhof presenta razas de animales dom\u00e9sticos en peligro de extinci\u00f3n en sus establos.<\/li>\n<li><strong>Pabell\u00f3n Imperial:<\/strong> En el coraz\u00f3n del Tiergarten se encuentra el Pabell\u00f3n Imperial, que una vez sirvi\u00f3 a la pareja imperial, el Emperador Francisco I y Mar\u00eda Teresa, como desayuno y sal\u00f3n social. Hoy es un caf\u00e9-restaurante que a\u00fan emana un estilo imperial con sus grandiosos frescos en el techo, pinturas al \u00f3leo y espejos. M\u00e1s sobre esto <a href=\"https:\/\/zoovienna-gastro.at\/unsere-betriebe\" rel=\"noopener\" target=\"_blank\">aqu\u00ed<\/a> .<\/li>\n<li><strong>Casa de las Palmeras:<\/strong> La Casa de las Palmeras de 1882 es una de las m\u00e1s grandes de su tipo en el mundo. Aqu\u00ed, los amantes de las plantas mediterr\u00e1neas, tropicales y subtropicales pueden maravillarse con diferentes tipos de plantas de tres zonas clim\u00e1ticas en tres pabellones. Los precios de las entradas y los horarios de apertura se pueden encontrar <a href=\"https:\/\/www.bundesgaerten.at\/schlosspark-schoenbrunn\/das-grosse-palmenhaus.html\" rel=\"noopener\" target=\"_blank\">aqu\u00ed<\/a> .<\/li>\n<li><strong>Casa del desierto:<\/strong> La casa del desierto justo enfrente de la <a href=\"https:\/\/viennatouristinformation.com\/es\/sehenswuerdigkeiten\/attraktionen\/\">casa de las palmeras<\/a> ofrece una experiencia en el desierto . La antigua casa del reloj de sol lleva a sus visitantes por un sendero de aventuras a trav\u00e9s de aut\u00e9nticos paisajes des\u00e9rticos desde Am\u00e9rica Central hasta Madagascar. Los precios de las entradas y los horarios de apertura se pueden encontrar <a href=\"https:\/\/www.zoovienna.at\/anlagen\/wuestenhaus\/\" rel=\"noopener\" target=\"_blank\">aqu\u00ed<\/a> .<\/li>\n<\/ul>\n<h2 id=\"t-1669899315264\" style=\"\">Accesos, parking y transporte p\u00fablico<\/h2>\n<p><span><img decoding=\"async\" alt=\"Giraffe mit BlickEing\u00e4nge, Parken und \u00d6ffentlicher Verkehr\" data-id=\"1958\" width=\"885\" data-init-width=\"1000\" height=\"590\" data-init-height=\"667\" title=\"Eing\u00e4nge, Parken und \u00d6ffentlicher Verkehr\" loading=\"lazy\" src=\"\/\/viennatouristinformation.com\/es\/wp-content\/uploads\/2020\/09\/Eing\u00e4nge-Parken-und-\u00d6ffentlicher-Verkehr.jpg\" data-width=\"885\" data-height=\"590\" data-pin-media=\"https:\/\/viennatouristinformation.com\/es\/wp-content\/uploads\/2021\/01\/wien_pinterest_tiergarten-2.jpg\" data-pin-description=\"Zool\u00f3gico de Sch\u00f6nbrunn Viena: animales, visitas y consejos de viaje\" data-pin-url=\"https:\/\/viennatouristinformation.com\/es\/cosas-que-hacer\/atracciones\/zoologico-de-schoenbrunn\/?tve=true&amp;tcbf=d5716ea3f9\" data-pinpro-key=\"zkcltt2hw\" style=\"aspect-ratio: auto 1000 \/ 667;\"><\/span><\/p>\n<h3 id=\"t-1669899315265\">Entradas:<\/h3>\n<ul>\n<li>\n<p><strong>Entrada principal de Hietzing:<\/strong> puede llegar a la entrada principal del zool\u00f3gico de Sch\u00f6nbrunn a trav\u00e9s de Hietzinger Tor. La parada m\u00e1s cercana es la estaci\u00f3n de metro Hietzing.<\/p>\n<\/li>\n<li>\n<p><strong>Entrada Tirolerhof:<\/strong> Esta entrada est\u00e1 en Seckendorff-Gudent-Weg. Si llegas en coche y aparcas en el parking p\u00fablico, esta es la entrada m\u00e1s cercana.<\/p>\n<\/li>\n<li><strong>Entrada Neptun:<\/strong> Esta entrada se encuentra en el <a href=\"https:\/\/viennatouristinformation.com\/es\/sehenswuerdigkeiten\/schonbrunn\/\">Parque del Palacio de Sch\u00f6nbrunn<\/a> . Se encuentra en el lado del castillo junto a la fuente de Neptuno.<\/li>\n<\/ul>\n<h3 id=\"t-1669899315266\">El parque:<\/h3>\n<ul>\n<li>Un aparcamiento p\u00fablico est\u00e1 disponible para los visitantes del zool\u00f3gico en Seckendorff-Gudent-Weg. El acceso es a trav\u00e9s de Elisabeth-Allee. Los espacios de estacionamiento son limitados. Direcci\u00f3n: Seckendorff-Gudent-Weg, 1130 Viena.<\/li>\n<li>Tambi\u00e9n hay un aparcamiento de pago APCOA con 160 plazas en el Palacio de <a href=\"https:\/\/viennatouristinformation.com\/es\/sehenswuerdigkeiten\/schonbrunn\/\">Sch\u00f6nbrunn . <\/a>Desde aqu\u00ed puede llegar al Tiergarten en unos 22 minutos a pie. Direcci\u00f3n: Sch\u00f6nbrunner Schlo\u00dfstrasse 50, 1130 Viena.<\/li>\n<\/ul>\n<h3 id=\"t-1669899315267\"><strong>Transporte<\/strong> p\u00fablico :<strong><\/strong><\/h3>\n<ul>\n<li><strong>U-Bahn:<\/strong> U4 Hietzing<\/li>\n<li><strong>Tranv\u00eda:<\/strong> 10, 58, 60 Hietzing U (Puente Kennedy)<\/li>\n<li><strong>Autobuses:<\/strong> 51A, 56A, 56B, 58A<\/li>\n<\/ul>\n<h2 id=\"t-1669899315268\" style=\"\">Comer en el zool\u00f3gico<\/h2>\n<p><span><img decoding=\"async\" alt=\"Essen im Tiergarten\" data-id=\"1959\" width=\"885\" data-init-width=\"1000\" height=\"590\" data-init-height=\"667\" title=\"Essen im Tiergarten\" loading=\"lazy\" src=\"\/\/viennatouristinformation.com\/es\/wp-content\/uploads\/2020\/09\/Essen-im-Tiergarten.jpg\" data-width=\"885\" data-height=\"590\" data-pin-media=\"https:\/\/viennatouristinformation.com\/es\/wp-content\/uploads\/2021\/01\/wien_pinterest_tiergarten-2.jpg\" data-pin-description=\"Zool\u00f3gico de Sch\u00f6nbrunn Viena: animales, visitas y consejos de viaje\" data-pin-url=\"https:\/\/viennatouristinformation.com\/es\/cosas-que-hacer\/atracciones\/zoologico-de-schoenbrunn\/?tve=true&amp;tcbf=d5716ea3f9\" data-pinpro-key=\"d4wot53qr\" style=\"aspect-ratio: auto 1000 \/ 667;\"><\/span><\/p>\n<p>Numerosos restaurantes y caf\u00e9s en el Tiergarten brindan bienestar f\u00edsico a los visitantes. Adem\u00e1s del ya mencionado Kaiserpavillon y el Caf\u00e9 Atelier Nonja, puede disfrutar de una excelente comida en el r\u00fastico Gasthaus Tirolergarten, en el Jumbo Grillgarten o en la cervecer\u00eda al aire libre.<\/p>\n<p>El Caf\u00e9 Hietzing en la entrada de Hietzing, el Landtmann&#8217;s Parkcaf\u00e9 en el parque del castillo y el Eissalon Rhino Bar, donde puede disfrutar de un delicioso helado, son todos adecuados para una pausa para el caf\u00e9.<\/p>\n<h2 id=\"t-1669899315269\" style=\"\">Historia del zoologico<\/h2>\n<p><span><img decoding=\"async\" alt=\"Geschichte des Tiergarten\" data-id=\"1960\" width=\"885\" data-init-width=\"1000\" height=\"590\" data-init-height=\"667\" title=\"Geschichte des Tiergarten\" loading=\"lazy\" src=\"\/\/viennatouristinformation.com\/es\/wp-content\/uploads\/2020\/09\/Geschichte-des-Tiergarten.jpg\" data-width=\"885\" data-height=\"590\" data-pin-media=\"https:\/\/viennatouristinformation.com\/es\/wp-content\/uploads\/2021\/01\/wien_pinterest_tiergarten-2.jpg\" data-pin-description=\"Zool\u00f3gico de Sch\u00f6nbrunn Viena: animales, visitas y consejos de viaje\" data-pin-url=\"https:\/\/viennatouristinformation.com\/es\/cosas-que-hacer\/atracciones\/zoologico-de-schoenbrunn\/?tve=true&amp;tcbf=d5716ea3f9\" data-pinpro-key=\"nzwilmdtm\" style=\"aspect-ratio: auto 1000 \/ 667;\"><\/span><\/p>\n<p>El zool\u00f3gico fue inaugurado en 1752 por el emperador Francisco I Esteban de Lorena, esposo de Mar\u00eda Teresa, como una colecci\u00f3n imperial en el parque de la residencia de verano de Sch\u00f6nbrunn.<\/p>\n<p>El sistema se remonta a un dise\u00f1o del arquitecto de la corte Nicolas Jadot. Despu\u00e9s de un a\u00f1o de construcci\u00f3n, la casa de fieras se complet\u00f3 en 1752, con animales y presentada a los visitantes. El centro del complejo era el pabell\u00f3n central dise\u00f1ado como sala de desayunos, hoy el Pabell\u00f3n Imperial, que solo se complet\u00f3 en 1759. 13 recintos de animales dispuestos radialmente lo rodean.<\/p>\n<p>No fue hasta 1779 que el zool\u00f3gico, que albergaba cada vez m\u00e1s animales, se abri\u00f3 al p\u00fablico. Gracias a las expediciones a \u00c1frica y Am\u00e9rica organizadas por el emperador Jos\u00e9 II, cada vez llegaban m\u00e1s animales ex\u00f3ticos como elefantes y jirafas al zool\u00f3gico.<\/p>\n<p>Con el fin de la monarqu\u00eda, el zool\u00f3gico pas\u00f3 a ser propiedad de la Rep\u00fablica de Austria. Sin embargo, los cuellos de botella en el suministro y las deficiencias higi\u00e9nicas provocadas por la Primera Guerra Mundial hicieron que el n\u00famero de animales se redujera en casi un 85 por ciento.<\/p>\n<p>Bajo la direcci\u00f3n del bi\u00f3logo Otto Antonius, el n\u00famero de animales volvi\u00f3 a aumentar considerablemente hasta 1930. Tambi\u00e9n introdujo la idea de criar especies animales en peligro de extinci\u00f3n.<\/p>\n<p>Desafortunadamente, el zool\u00f3gico no se salv\u00f3 del bombardeo de la Segunda Guerra Mundial. Muchos de los animales residentes perdieron la vida.<\/p>\n<p>Despu\u00e9s del extenso trabajo de restauraci\u00f3n, el zool\u00f3gico se encontr\u00f3 en una situaci\u00f3n financiera desesperada. Solo la privatizaci\u00f3n del zool\u00f3gico, los precios de entrada m\u00e1s altos y numerosos patrocinadores aseguraron que los recintos pudieran renovarse y ampliarse.<\/p>\n<p>El Tiergarten forma parte del Patrimonio de la Humanidad de la UNESCO de <a href=\"https:\/\/viennatouristinformation.com\/es\/sehenswuerdigkeiten\/schonbrunn\/\">Sch\u00f6nbrunn<\/a> desde 1996 .<\/p>\n<p>Incluso hoy en d\u00eda, el zool\u00f3gico en funcionamiento continuo m\u00e1s antiguo del mundo emana un estilo hist\u00f3rico. El Zool\u00f3gico de Sch\u00f6nbrunn es ahora el hogar de m\u00e1s de 750 especies de animales de todos los continentes y est\u00e1 dedicado a la preservaci\u00f3n y protecci\u00f3n de especies en peligro de extinci\u00f3n.<\/p>\n<h2 id=\"t-1669899315270\" style=\"\">Contacto<\/h2>\n<ul>\n<li><strong>Direcci\u00f3n:<\/strong> Maxingstrasse 13b, 1130 Viena<\/li>\n<li><strong>U-Bahn: &nbsp;<\/strong> U4 Hietzing<\/li>\n<li><strong>Horario de apertura:<\/strong> el zool\u00f3gico de Sch\u00f6nbrunn est\u00e1 abierto todos los d\u00edas. Los horarios de apertura actuales se pueden encontrar <a href=\"https:\/\/www.zoovienna.at\/besuch-und-tickets\/besucherinformation\/#oeffnungszeiten\" rel=\"noopener\" target=\"_blank\">aqu\u00ed<\/a> .<\/li>\n<\/ul>\n<h3 style=\"\" id=\"t-1686571213368\"><strong>ART\u00cdCULOS RELACIONADOS<\/strong><\/h3>\n<p><a href=\"https:\/\/viennatouristinformation.com\/es\/cosas-que-hacer\/atracciones\/prater\/\" dynamic-postlink=\"tcb_post_the_permalink\" data-shortcode-id=\"822\"><\/a><\/p>\n<h2 style=\"padding-top: 0px !important; margin-top: 0px !important; text-align: center;\" id=\"t-1686745641878\" data-hide=\"true\"><span data-shortcode=\"tcb_post_title\" data-shortcode-name=\"Post title\" data-extra_key=\"\" data-attr-link=\"1\" data-attr-target=\"0\" data-attr-rel=\"0\" data-option-inline=\"1\" data-attr-static-link=\"{&quot;className&quot;:&quot;&quot;,&quot;href&quot;:&quot;https:\/\/viennatouristinformation.com\/es\/cosas-que-hacer\/museo\/&quot;,&quot;title&quot;:&quot;30 Museos m\u00e1s importantes de Viena&quot;,&quot;class&quot;:&quot;&quot;}\" data-attr-css=\"\"><a href=\"https:\/\/viennatouristinformation.com\/es\/cosas-que-hacer\/atracciones\/prater\/\" title=\"Prater en Viena: Principales atracciones, entrada e historia\" data-css=\"\">Prater en Viena: Principales atracciones, entrada e historia<\/a><\/span><\/h2>\n<p><a href=\"https:\/\/viennatouristinformation.com\/es\/cosas-que-hacer\/atracciones\/rueda-de-la-fortuna\/\" dynamic-postlink=\"tcb_post_the_permalink\" data-shortcode-id=\"822\"><\/a><\/p>\n<h2 style=\"padding-top: 0px !important; margin-top: 0px !important; text-align: center;\" id=\"t-1686745641878\" data-hide=\"true\"><span data-shortcode=\"tcb_post_title\" data-shortcode-name=\"Post title\" data-extra_key=\"\" data-attr-link=\"1\" data-attr-target=\"0\" data-attr-rel=\"0\" data-option-inline=\"1\" data-attr-static-link=\"{&quot;className&quot;:&quot;&quot;,&quot;href&quot;:&quot;https:\/\/viennatouristinformation.com\/es\/cosas-que-hacer\/museo\/&quot;,&quot;title&quot;:&quot;30 Museos m\u00e1s importantes de Viena&quot;,&quot;class&quot;:&quot;&quot;}\" data-attr-css=\"\"><a href=\"https:\/\/viennatouristinformation.com\/es\/cosas-que-hacer\/atracciones\/rueda-de-la-fortuna\/\" title=\"Rueda de la fortuna: Visita a un lugar emblem\u00e1tico de Viena\" data-css=\"\">Rueda de la fortuna: Visita a un lugar emblem\u00e1tico de Viena<\/a><\/span><\/h2>\n<p><a href=\"https:\/\/viennatouristinformation.com\/es\/cosas-que-hacer\/atracciones\/ayuntamiento\/\" dynamic-postlink=\"tcb_post_the_permalink\" data-shortcode-id=\"822\"><\/a><\/p>\n<h2 style=\"padding-top: 0px !important; margin-top: 0px !important; text-align: center;\" id=\"t-1686745641878\" data-hide=\"true\"><span data-shortcode=\"tcb_post_title\" data-shortcode-name=\"Post title\" data-extra_key=\"\" data-attr-link=\"1\" data-attr-target=\"0\" data-attr-rel=\"0\" data-option-inline=\"1\" data-attr-static-link=\"{&quot;className&quot;:&quot;&quot;,&quot;href&quot;:&quot;https:\/\/viennatouristinformation.com\/es\/cosas-que-hacer\/museo\/&quot;,&quot;title&quot;:&quot;30 Museos m\u00e1s importantes de Viena&quot;,&quot;class&quot;:&quot;&quot;}\" data-attr-css=\"\"><a href=\"https:\/\/viennatouristinformation.com\/es\/cosas-que-hacer\/atracciones\/ayuntamiento\/\" title=\"Ayuntamiento de Viena: Rathausplatz, eventos y visitas\" data-css=\"\">Ayuntamiento de Viena: Rathausplatz, eventos y visitas<\/a><\/span><\/h2>\n<p><a href=\"https:\/\/viennatouristinformation.com\/es\/cosas-que-hacer\/parques\/\" dynamic-postlink=\"tcb_post_the_permalink\" data-shortcode-id=\"822\"><\/a><\/p>\n<h2 style=\"padding-top: 0px !important; margin-top: 0px !important; text-align: center;\" id=\"t-1686745641878\" data-hide=\"true\"><span data-shortcode=\"tcb_post_title\" data-shortcode-name=\"Post title\" data-extra_key=\"\" data-attr-link=\"1\" data-attr-target=\"0\" data-attr-rel=\"0\" data-option-inline=\"1\" data-attr-static-link=\"{&quot;className&quot;:&quot;&quot;,&quot;href&quot;:&quot;https:\/\/viennatouristinformation.com\/es\/cosas-que-hacer\/museo\/&quot;,&quot;title&quot;:&quot;30 Museos m\u00e1s importantes de Viena&quot;,&quot;class&quot;:&quot;&quot;}\" data-attr-css=\"\"><a href=\"https:\/\/viennatouristinformation.com\/es\/cosas-que-hacer\/parques\/\" title=\"20 Parques m\u00e1s bonitos de Viena\" data-css=\"\">20 Parques m\u00e1s bonitos de Viena<\/a><\/span><\/h2>\n","protected":false},"excerpt":{"rendered":"<p>El zool\u00f3gico de Sch\u00f6nbrunn en el parque del palacio, en los terrenos del famoso Palacio de Sch\u00f6nbrunn , es el zool\u00f3gico m\u00e1s antiguo del mundo. Fue fundado en 1752 por el emperador Francisco I Esteban de Lorena, esposo de Mar\u00eda Teresa. No solo es parte del Patrimonio de la Humanidad de la UNESCO de Sch\u00f6nbrunn, [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":1954,"parent":138,"menu_order":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"footnotes":"","tve_updated_post":"<div class=\"thrv_wrapper thrv_text_element\"><h2 class=\"\" id=\"t-1669899315257\" data-hide=\"true\"><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\">El zool\u00f3gico de Sch\u00f6nbrunn en el parque del palacio, en los terrenos del famoso Palacio de <\/font><\/font><a href=\"https:\/\/viennatouristinformation.com\/es\/cosas-que-hacer\/castillos\/schoenbrunn\/\" class=\"\" style=\"outline: none;\"><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\">Sch\u00f6nbrunn<\/font><\/font><\/a><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\"> , es el zool\u00f3gico m\u00e1s antiguo del mundo.<\/font><\/font><\/h2><p><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\">Fue fundado en 1752 por el emperador Francisco I Esteban de Lorena, esposo de Mar\u00eda Teresa.<\/font><\/font><\/p><p><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\">No solo es parte del Patrimonio de la Humanidad de la UNESCO de Sch\u00f6nbrunn, sino que tambi\u00e9n ha sido nombrado \"Mejor zool\u00f3gico de Europa\" cinco veces seguidas.<\/font><\/font><\/p><p><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\">Con m\u00e1s de 2 millones de visitantes al a\u00f1o, el zool\u00f3gico es una <\/font><\/font><a href=\"https:\/\/viennatouristinformation.com\/es\/cosas-que-hacer\/\" class=\"\" style=\"outline: none;\"><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\">de las atracciones m\u00e1s visitadas de Viena<\/font><\/font><\/a><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\"> .<\/font><\/font><\/p><p style=\"\" data-css=\"tve-u-188b9e13e8e\"><strong><font><font>Otros art\u00edculos recomendados:<\/font><\/font><br><\/strong><\/p><ul class=\"\"><li><a href=\"https:\/\/viennatouristinformation.com\/es\/cosas-que-hacer\/10-mejores\/\" class=\"\" style=\"outline: none;\"><font><font>Las 10 mejores cosas que hacer en Viena<\/font><\/font><\/a><\/li><li><a href=\"https:\/\/viennatouristinformation.com\/es\/hoteles\/\" class=\"\" style=\"outline: none;\"><font><font>Los hoteles mejor recomendados en Viena<\/font><\/font><\/a><\/li><li><a href=\"https:\/\/viennatouristinformation.com\/es\/cosas-que-hacer\/atracciones\/\"><font><font>Atracciones excepcionales en Viena<\/font><\/font><\/a><\/li><li><a href=\"https:\/\/viennatouristinformation.com\/es\/comida\/\"><font><font>Los mejores restaurantes de Viena<\/font><\/font><\/a><\/li><li><a href=\"https:\/\/viennatouristinformation.com\/es\/compras\/\"><font><font>Compras en Viena<\/font><\/font><\/a><\/li><li><a href=\"https:\/\/viennatouristinformation.com\/es\/plan\/transporte-publico\/\"><font><font>Transporte p\u00fablico en Viena<\/font><\/font><\/a><\/li><\/ul><\/div><div class=\"thrv_wrapper tve-toc tve-toc-expandable tcb-local-vars-root\" data-columns=\"1\" data-ct=\"toc-60672\" data-transition=\"slide\" data-headers=\"h2\" data-numbering=\"none\" data-highlight=\"none\" data-ct-name=\"Table of Contents 04\" data-heading-style=\"{&quot;0&quot;:&quot;tve-u-184cdc5e803&quot;,&quot;1&quot;:&quot;tve-u-184cdc5e805&quot;,&quot;2&quot;:&quot;tve-u-184cdc5e806&quot;}\" style=\"\" data-css=\"tve-u-184cdc5e7fc\" data-bullet-style=\"{&quot;0&quot;:&quot;tve-u-1739a1b9ec9&quot;,&quot;1&quot;:&quot;tve-u-1739a1ba9d6&quot;,&quot;2&quot;:&quot;tve-u-1739a1bb53c&quot;}\" data-number-style=\"{&quot;0&quot;:&quot;tve-u-184cdc5e804&quot;,&quot;1&quot;:&quot;tve-u-173dc88e09d&quot;,&quot;2&quot;:&quot;tve-u-173dc88e7b7&quot;}\" data-state-default=\"expanded\" data-animation=\"fade\" data-animation-speed=\"fast\" data-columns-d=\"2\" data-state-default-m=\"collapsed\" data-element-name=\"Table of Contents\" data-state-default-d=\"expanded\" data-distribute=\"true\" data-id=\"livoxj6r\"><div class=\"thrive-colors-palette-config\" style=\"display: none !important\">__CONFIG_colors_palette__{\"active_palette\":0,\"config\":{\"colors\":{\"4b31d\":{\"name\":\"Main Accent\",\"parent\":-1},\"5fb35\":{\"name\":\"Accent Dark\",\"parent\":\"4b31d\",\"lock\":{\"saturation\":1}}},\"gradients\":[]},\"palettes\":[{\"name\":\"Default\",\"value\":{\"colors\":{\"4b31d\":{\"val\":\"var(--tcb-skin-color-0)\"},\"5fb35\":{\"val\":\"rgb(64, 59, 59)\",\"hsl_parent_dependency\":{\"h\":358,\"l\":0.24,\"s\":0.04}}},\"gradients\":[]},\"original\":{\"colors\":{\"4b31d\":{\"val\":\"rgb(51, 190, 127)\",\"hsl\":{\"h\":152,\"s\":0.57,\"l\":0.47,\"a\":1}},\"5fb35\":{\"val\":\"rgb(59, 65, 63)\",\"hsl_parent_dependency\":{\"h\":160,\"s\":0.04,\"l\":0.24,\"a\":1}}},\"gradients\":[]}}]}__CONFIG_colors_palette__<\/div><div class=\"tve-toc-divider\" style=\"position: absolute; width: 0; height: 0; overflow: hidden;\"><div class=\"thrv_wrapper thrv-divider tve-vert-divider\" data-style=\"tve_sep-1\" data-color-d=\"rgba(0, 0, 0, 0.24)\" data-css=\"tve-u-184cdc5e7fd\" data-style-d=\"tve_sep-3\" data-thickness-d=\"6\"><hr class=\"tve_sep tve_sep-3\" style=\"\"><\/div><\/div><svg class=\"toc-icons\" style=\"position: absolute; width: 0; height: 0; overflow: hidden;\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><symbol viewBox=\"0 0 512 512\" id=\"toc-bullet-0-livoxj6r\" data-id=\"icon-clone-outlined\"><path d=\"M464 0H144c-26.51 0-48 21.49-48 48v48H48c-26.51 0-48 21.49-48 48v320c0 26.51 21.49 48 48 48h320c26.51 0 48-21.49 48-48v-48h48c26.51 0 48-21.49 48-48V48c0-26.51-21.49-48-48-48zM362 464H54a6 6 0 0 1-6-6V150a6 6 0 0 1 6-6h42v224c0 26.51 21.49 48 48 48h224v42a6 6 0 0 1-6 6zm96-96H150a6 6 0 0 1-6-6V54a6 6 0 0 1 6-6h308a6 6 0 0 1 6 6v308a6 6 0 0 1-6 6z\"><\/path><\/symbol><symbol id=\"toc-bullet-1-livoxj6r\" viewBox=\"0 0 192 512\" data-id=\"icon-caret-right-solid\">\n            <path d=\"M0 384.662V127.338c0-17.818 21.543-26.741 34.142-14.142l128.662 128.662c7.81 7.81 7.81 20.474 0 28.284L34.142 398.804C21.543 411.404 0 402.48 0 384.662z\"><\/path>\n        <\/symbol><symbol id=\"toc-bullet-2-livoxj6r\" viewBox=\"0 0 192 512\" data-id=\"icon-caret-right-solid\">\n            <path d=\"M0 384.662V127.338c0-17.818 21.543-26.741 34.142-14.142l128.662 128.662c7.81 7.81 7.81 20.474 0 28.284L34.142 398.804C21.543 411.404 0 402.48 0 384.662z\"><\/path>\n        <\/symbol><\/svg>\n\t<div class=\"tve-content-box-background\" style=\"\" data-css=\"tve-u-184cdc5e7fe\"><\/div>\n\t<div class=\"thrv_wrapper tve-toc-title show-icon reverse tcb-icon-display tve-no-dropzone tve-prevent-content-edit\" data-css=\"tve-u-184cdc5e7ff\" style=\"\">\n\t<div class=\"tve-content-box-background\"><\/div>\n\t<div class=\"tve-cb\" style=\"\">\n\t\t<div class=\"tve-toc-title-icon\" data-icon-code=\"icon-close-solid\" style=\"\"><svg class=\"tcb-icon\" viewBox=\"0 0 24 24\" data-id=\"icon-close-solid\" data-name=\"\"><path d=\"M19,6.41L17.59,5L12,10.59L6.41,5L5,6.41L10.59,12L5,17.59L6.41,19L12,13.41L17.59,19L19,17.59L13.41,12L19,6.41Z\"><\/path><\/svg><\/div>\n\t\t<div class=\"thrv_wrapper thrv_text_element tve_no_icons\"><div class=\"tcb-plain-text\" style=\"text-align: center;\" data-css=\"tve-u-184cdc5e800\"><strong><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\">Tabla de contenido<\/font><\/font><\/strong><\/div><\/div>\n\t<\/div>\n<\/div><div class=\"tve-cb tve-toc-content tve-prevent-content-edit\">\n\t\t\n\n\t\t<div class=\"thrv_wrapper tve-toc-list tcb-no-delete tcb-no-save tcb-no-clone tve-no-dropzone\" data-css=\"tve-u-184cdc5e801\" style=\"\">\n\t\t\t<div class=\"tve-content-box-background\" data-css=\"tve-u-184cdc5e802\"><\/div>\n\t\t\t<div class=\"tve-cb\">\n\t\t\t\t<div class=\"tve_ct_content tve_clearfix\"><div class=\"ct_column\"><div class=\"thrv_wrapper tve-toc-heading tve-toc-heading-level0 tve_no_icons\" data-tag=\"H2\" data-css=\"tve-u-184cdc5e803\" data-element-name=\"Heading Level 1\"><a href=\"#t-1669899315258\" class=\"tve-toc-anchor tve-jump-scroll\" jump-animation=\"smooth\">\u00bfQu\u00e9 animales puedo ver en el zool\u00f3gico de Sch\u00f6nbrunn?<\/a><\/div><div class=\"thrv_wrapper tve-toc-heading tve-toc-heading-level0 tve_no_icons\" data-tag=\"H2\" data-css=\"tve-u-184cdc5e803\" data-element-name=\"Heading Level 1\"><a href=\"#t-1669899315259\" class=\"tve-toc-anchor tve-jump-scroll\" jump-animation=\"smooth\">Precios: Entrada, entrada y pase anual<\/a><\/div><div class=\"thrv_wrapper tve-toc-heading tve-toc-heading-level0 tve_no_icons\" data-tag=\"H2\" data-css=\"tve-u-184cdc5e803\" data-element-name=\"Heading Level 1\"><a href=\"#t-1669899315260\" class=\"tve-toc-anchor tve-jump-scroll\" jump-animation=\"smooth\">Descuentos y vales<\/a><\/div><div class=\"thrv_wrapper tve-toc-heading tve-toc-heading-level0 tve_no_icons\" data-tag=\"H2\" data-css=\"tve-u-184cdc5e803\" data-element-name=\"Heading Level 1\"><a href=\"#t-1669899315263\" class=\"tve-toc-anchor tve-jump-scroll\" jump-animation=\"smooth\">Lugares de inter\u00e9s en el Tiergarten<\/a><\/div><\/div><div class=\"thrv_wrapper thrv-divider tve-vert-divider\" data-style=\"tve_sep-1\" data-color-d=\"rgba(0, 0, 0, 0.24)\" data-css=\"tve-u-184cdc5e7fd\" data-style-d=\"tve_sep-3\" data-thickness-d=\"6\"><hr class=\"tve_sep tve_sep-3\" style=\"\"><\/div><div class=\"ct_column\"><div class=\"thrv_wrapper tve-toc-heading tve-toc-heading-level0 tve_no_icons\" data-tag=\"H2\" data-css=\"tve-u-184cdc5e803\" data-element-name=\"Heading Level 1\"><a href=\"#t-1669899315264\" class=\"tve-toc-anchor tve-jump-scroll\" jump-animation=\"smooth\">Accesos, parking y transporte p\u00fablico<\/a><\/div><div class=\"thrv_wrapper tve-toc-heading tve-toc-heading-level0 tve_no_icons\" data-tag=\"H2\" data-css=\"tve-u-184cdc5e803\" data-element-name=\"Heading Level 1\"><a href=\"#t-1669899315268\" class=\"tve-toc-anchor tve-jump-scroll\" jump-animation=\"smooth\">Comer en el zool\u00f3gico<\/a><\/div><div class=\"thrv_wrapper tve-toc-heading tve-toc-heading-level0 tve_no_icons\" data-tag=\"H2\" data-css=\"tve-u-184cdc5e803\" data-element-name=\"Heading Level 1\"><a href=\"#t-1669899315269\" class=\"tve-toc-anchor tve-jump-scroll\" jump-animation=\"smooth\">Historia del zoologico<\/a><\/div><div class=\"thrv_wrapper tve-toc-heading tve-toc-heading-level0 tve_no_icons\" data-tag=\"H2\" data-css=\"tve-u-184cdc5e803\" data-element-name=\"Heading Level 1\"><a href=\"#t-1669899315270\" class=\"tve-toc-anchor tve-jump-scroll\" jump-animation=\"smooth\">Contacto<\/a><\/div><\/div><div class=\"thrv_wrapper thrv-divider tve-vert-divider\" data-style=\"tve_sep-1\" data-color-d=\"rgba(0, 0, 0, 0.24)\" data-css=\"tve-u-184cdc5e7fd\" data-style-d=\"tve_sep-3\" data-thickness-d=\"6\"><hr class=\"tve_sep tve_sep-3\" style=\"\"><\/div><\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div><div class=\"thrv_wrapper thrv_text_element\"><h2 id=\"t-1669899315258\" class=\"\" style=\"\" data-css=\"tve-u-188b9e1851f\"><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\">\u00bfQu\u00e9 animales puedo ver en el zool\u00f3gico de Sch\u00f6nbrunn?<\/font><\/font><\/h2><\/div><div class=\"thrv_wrapper tve_image_caption\" data-css=\"tve-u-184cdcaef78\"><span class=\"tve_image_frame\"><img decoding=\"async\" class=\"tve_image wp-image-1955 pin-process\" alt=\"Welche Tiere kann ich im Tiergarten Sch\u00f6nbrunn sehen\" data-id=\"1955\" width=\"885\" data-init-width=\"1000\" height=\"590\" data-init-height=\"667\" title=\"Welche Tiere kann ich im Tiergarten Sch\u00f6nbrunn sehen\" loading=\"lazy\" src=\"\/\/viennatouristinformation.com\/es\/wp-content\/uploads\/2020\/09\/Welche-Tiere-kann-ich-im-Tiergarten-Sch\u00f6nbrunn-sehen.jpg\" data-width=\"885\" data-height=\"590\" data-pin-media=\"http:\/\/viennatouristinformation.com\/es\/wp-content\/uploads\/2021\/01\/wien_pinterest_tiergarten-2.jpg\" data-pin-description=\"Zool\u00f3gico de Sch\u00f6nbrunn Viena: animales, visitas y consejos de viaje\" data-pin-url=\"https:\/\/viennatouristinformation.com\/es\/cosas-que-hacer\/atracciones\/zoologico-de-schoenbrunn\/?tve=true&amp;tcbf=d5716ea3f9\" data-pinpro-key=\"q17w4csuk\" style=\"aspect-ratio: auto 1000 \/ 667;\"><\/span><\/div><div class=\"thrv_wrapper thrv_text_element\"><p><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\">M\u00e1s de 750 especies de animales y 8.000 animales llaman hogar al zool\u00f3gico de Sch\u00f6nbrunn.<\/font><\/font><\/p><p><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\">Aqu\u00ed hay una peque\u00f1a selecci\u00f3n:<\/font><\/font><\/p><ul class=\"\"><li><strong><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\">Osos polares:<\/font><\/font><\/strong><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\"> los gigantes blancos le dan la bienvenida al mundo de los osos polares de 1.700 m\u00b2 \"Franz Josef Land\". <\/font><font style=\"vertical-align: inherit;\">La osa polar reci\u00e9n nacida Finja, que se ha ganado los corazones de los visitantes desde que naci\u00f3 en noviembre de 2019, es particularmente popular.<\/font><\/font><\/li><li><strong><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\">Pandas:<\/font><\/font><\/strong><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\"> Los pandas, uno de los mam\u00edferos m\u00e1s raros del mundo, atraen multitudes.<\/font><\/font><\/li><li><strong><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\">Elefantes<\/font><\/font><\/strong><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\"> : Los elefantes africanos tambi\u00e9n son muy populares. <\/font><font style=\"vertical-align: inherit;\">Desde julio de 2019, la ni\u00f1a elefante Kibali ha deleitado a todos.<\/font><\/font><\/li><li><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\">Leones: en el zool\u00f3gico de Sch\u00f6nbrunn, tambi\u00e9n puede maravillarse con los poderosos leones que deambulan por su territorio.<\/font><\/font><\/li><li><strong><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\">Orangutanes:<\/font><\/font><\/strong><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\"> En ORANG.erie, los visitantes pueden ver orangutanes haciendo gimnasia, columpi\u00e1ndose y relaj\u00e1ndose. <\/font><font style=\"vertical-align: inherit;\">Adem\u00e1s del recinto al aire libre, ORANG.erie tambi\u00e9n posee el <\/font><\/font><em><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\">Caf\u00e9 Atelier Nonja<\/font><\/font><\/em><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\"> con una vista directa de los grandes simios.<\/font><\/font><\/li><li><strong><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\">Casa de los monos:<\/font><\/font><\/strong><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\"> La casa de los monos es el hogar de seis especies de monos: colobo, l\u00e9mur rufo rojo, tit\u00ed pigmeo, tit\u00ed emperador y tit\u00ed, y monos ardilla. <\/font><font style=\"vertical-align: inherit;\">Suricatas tambi\u00e9n viven en el complejo.<\/font><\/font><\/li><li><strong><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\">Casa acuario y terrario:<\/font><\/font><\/strong><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\"> Este entorno alberga el <\/font><\/font><em><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\">pabell\u00f3n<\/font><\/font><\/em><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\"> de cocodrilos con cocodrilos, tortugas y serpientes antenas, la casa <\/font><\/font><em><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\">acuario<\/font><\/font><\/em><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\"> con una amplia gama de especies de peces, incluidas especies de peces en peligro de extinci\u00f3n, pira\u00f1as y arapaimas gigantes, as\u00ed como la <\/font><\/font><em><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\">casa terrario<\/font><\/font><\/em><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\"> con numerosos reptiles como como iguanas rinoceronte, una gran anaconda, cobras, serpientes de cascabel y muchos m\u00e1s.<\/font><\/font><\/li><li><strong><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\">Jirafas:<\/font><\/font><\/strong><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\"> Las dos jirafas \"adolescentes\" Fleur y Sofie, las residentes del parque de jirafas, tambi\u00e9n est\u00e1n muy entusiasmadas.<\/font><\/font><\/li><li><strong><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\">Rinocerontes:<\/font><\/font><\/strong><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\"> el parque de rinocerontes de 6.000 m\u00b2 no solo est\u00e1 habitado por rinocerontes indios, sino que tambi\u00e9n viven aqu\u00ed otras especies asi\u00e1ticas como ant\u00edlopes nilgai, ciervos sika vietnamitas y ant\u00edlopes negros.<\/font><\/font><\/li><li><strong><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\">Polarium<\/font><\/font><\/strong><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\"> : En el Polarium se pueden admirar focas de crin, ping\u00fcinos de penacho amarillo y ping\u00fcinos rey a trav\u00e9s del vaso de la piscina de 13 metros de largo <\/font><\/font><strong><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\">.<\/font><\/font><\/strong><\/li><li><strong><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\">Rainforest<\/font><\/font><\/strong><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\"> House: esta enorme casa de cristal ocupa parte de la ladera de una monta\u00f1a en la selva tropical del sudeste asi\u00e1tico. <\/font><font style=\"vertical-align: inherit;\">Adem\u00e1s de la variedad de plantas, tambi\u00e9n hay numerosas especies animales, como nutrias pigmeas, tortugas de r\u00edo, pitones tigre, iguanas de Fiji y murci\u00e9lagos de hoja de anteojos. <\/font><font style=\"vertical-align: inherit;\">Gracias a la tecnolog\u00eda y los efectos especiales, como tormentas el\u00e9ctricas, bocanadas de niebla y temperaturas tropicales, los visitantes pueden esperar una experiencia aut\u00e9ntica.<\/font><\/font><\/li><li><strong><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\">South America Park:<\/font><\/font><\/strong><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\"> este h\u00e1bitat, modelado agr\u00edcolamente a partir de una pampa, alberga osos hormigueros gigantes, capibaras, tapires, vicu\u00f1as, seriemas y \u00f1and\u00faes.&nbsp; &nbsp;<\/font><\/font><\/li><li><strong><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\">Casa de \u00c1frica Oriental:<\/font><\/font><\/strong><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\"> aqu\u00ed retozan tokos, mangostas pigmeas y c\u00e1laos terrestres.<\/font><\/font><\/li><li><strong><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\">Sendero<\/font><\/font><\/strong><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\"> de descubrimiento de la naturaleza : Una atracci\u00f3n popular es el sendero de descubrimiento de la naturaleza que consta de tres etapas. <\/font><font style=\"vertical-align: inherit;\">Aqu\u00ed los visitantes pueden conocer mejor la flora y fauna local. <\/font><font style=\"vertical-align: inherit;\">Lo m\u00e1s destacado es el sendero de las copas de los \u00e1rboles de 160 metros de largo, donde puede pasear por un puente colgante de 10 metros de altura a trav\u00e9s de las copas de los \u00e1rboles de los bosques de Viena y <\/font><font style=\"vertical-align: inherit;\">disfrutar de maravillosas vistas del Palacio de <\/font><\/font><a href=\"https:\/\/viennatouristinformation.com\/es\/cosas-que-hacer\/castillos\/schoenbrunn\/\" class=\"\" style=\"outline: none;\"><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\">Sch\u00f6nbrunn .<\/font><\/font><\/a><font style=\"vertical-align: inherit;\"><\/font><\/li><\/ul><h2 id=\"t-1669899315259\" class=\"\" style=\"\" data-css=\"tve-u-188b9e19382\"><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\">Precios: Entrada, entrada y pase anual<\/font><\/font><\/h2><\/div><div class=\"thrv_wrapper tve_image_caption\" data-css=\"tve-u-184cdcb4929\"><span class=\"tve_image_frame\"><img decoding=\"async\" class=\"tve_image wp-image-1956 pin-process\" alt=\"Preise Eintritt, Ticket und Jahreskarte\" data-id=\"1956\" width=\"885\" data-init-width=\"1000\" height=\"590\" data-init-height=\"667\" title=\"Preise Eintritt, Ticket und Jahreskarte\" loading=\"lazy\" src=\"\/\/viennatouristinformation.com\/es\/wp-content\/uploads\/2020\/09\/Preise-Eintritt-Ticket-und-Jahreskarte.jpg\" data-width=\"885\" data-height=\"590\" data-pin-media=\"http:\/\/viennatouristinformation.com\/es\/wp-content\/uploads\/2021\/01\/wien_pinterest_tiergarten-2.jpg\" data-pin-description=\"Zool\u00f3gico de Sch\u00f6nbrunn Viena: animales, visitas y consejos de viaje\" data-pin-url=\"https:\/\/viennatouristinformation.com\/es\/cosas-que-hacer\/atracciones\/zoologico-de-schoenbrunn\/?tve=true&amp;tcbf=d5716ea3f9\" data-pinpro-key=\"dwiy92a4v\" style=\"aspect-ratio: auto 1000 \/ 667;\"><\/span><\/div><div class=\"thrv_wrapper thrv_text_element\"><ul class=\"\"><li><strong><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\">Entradas:<\/font><\/font><\/strong><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\"> Adultos pagan 22\u20ac por entrada de d\u00eda, ni\u00f1os y j\u00f3venes pagan 11\u20ac.<\/font><\/font><\/li><li><strong><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\">Entradas combinadas:<\/font><\/font><\/strong><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\"> el zool\u00f3gico de Sch\u00f6nbrunn ofrece varias entradas combinadas que los visitantes pueden usar para ahorrar. <\/font><font style=\"vertical-align: inherit;\">Puede encontrar una descripci\u00f3n general de todos los boletos combinados <\/font><\/font><a href=\"https:\/\/www.zoovienna.at\/besuch-und-tickets\/kombitickets\/\" rel=\"noopener\" target=\"_blank\"><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\">aqu\u00ed<\/font><\/font><\/a><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\"> .<\/font><\/font><\/li><li><strong><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\">Paquete ventaja:<\/font><\/font><\/strong><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\"> Existe un paquete ventaja por 65\u20ac, que consiste en entradas de 2 d\u00edas para adultos y entradas de 3 d\u00edas para ni\u00f1os\/adolescentes.<\/font><\/font><\/li><li><strong><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\">Visitas guiadas:<\/font><\/font><\/strong><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\"> Diversas visitas guiadas hacen de la visita una experiencia especial. <\/font><font style=\"vertical-align: inherit;\">Los horarios y precios actuales se pueden encontrar en la p\u00e1gina de <\/font><\/font><a href=\"https:\/\/www.zoovienna.at\/termine\/\" rel=\"noopener\" target=\"_blank\"><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\">inicio<\/font><\/font><\/a><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\"> del zool\u00f3gico .<\/font><\/font><\/li><li><strong><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\">Alimentaci\u00f3n:<\/font><\/font><\/strong><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\"> Las fechas actuales de las diversas alimentaciones, que son muy populares, se pueden encontrar <\/font><\/font><a href=\"https:\/\/www.zoovienna.at\/termine\/fuetterungen\/\" rel=\"noopener\" target=\"_blank\"><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\">aqu\u00ed<\/font><\/font><\/a><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\"> .<\/font><\/font><\/li><li><strong><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\">Pase anual :<\/font><\/font><\/strong><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\"> El zool\u00f3gico tambi\u00e9n ofrece un pase anual y es v\u00e1lido por un a\u00f1o a partir de la fecha de compra.<\/font><\/font><\/li><\/ul><h2 id=\"t-1669899315260\" class=\"\" style=\"\" data-css=\"tve-u-188b9e1a186\"><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\">Descuentos y vales<\/font><\/font><\/h2><\/div><div class=\"thrv_wrapper tve_image_caption\" data-css=\"tve-u-184cdcb95c6\"><span class=\"tve_image_frame\"><img decoding=\"async\" class=\"tve_image wp-image-1957 pin-process\" alt=\"Erm\u00e4\u00dfigungen und Gutscheine\" data-id=\"1957\" width=\"885\" data-init-width=\"1000\" height=\"590\" data-init-height=\"667\" title=\"Erm\u00e4\u00dfigungen und Gutscheine\" loading=\"lazy\" src=\"\/\/viennatouristinformation.com\/es\/wp-content\/uploads\/2020\/09\/Erm\u00e4\u00dfigungen-und-Gutscheine.jpg\" data-width=\"885\" data-height=\"590\" data-pin-media=\"http:\/\/viennatouristinformation.com\/es\/wp-content\/uploads\/2021\/01\/wien_pinterest_tiergarten-2.jpg\" data-pin-description=\"Zool\u00f3gico de Sch\u00f6nbrunn Viena: animales, visitas y consejos de viaje\" data-pin-url=\"https:\/\/viennatouristinformation.com\/es\/cosas-que-hacer\/atracciones\/zoologico-de-schoenbrunn\/?tve=true&amp;tcbf=d5716ea3f9\" data-pinpro-key=\"3s4q4yma1\" style=\"aspect-ratio: auto 1000 \/ 667;\"><\/span><\/div><div class=\"thrv_wrapper thrv_text_element\"><h3 id=\"t-1669899315261\" class=\"\" style=\"\" data-css=\"tve-u-188b9e1aa42\"><strong><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\">Descuentos:<\/font><\/font><\/strong><\/h3><ul class=\"\"><li><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\">Los ni\u00f1os y j\u00f3venes de 6 a 18 a\u00f1os pagan 11 \u20ac.<\/font><\/font><\/li><li><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\">Los ni\u00f1os hasta los 6 a\u00f1os disfrutan de entrada gratuita.<\/font><\/font><\/li><li><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\">Los ni\u00f1os y j\u00f3venes con discapacidad (hasta los 19 a\u00f1os) reciben entrada gratuita, y un acompa\u00f1ante tambi\u00e9n recibe una entrada reducida.<\/font><\/font><\/li><li><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\">Las personas con un grado de discapacidad igual o superior al 50% obtienen una entrada reducida previa presentaci\u00f3n de la tarjeta de discapacidad.<\/font><\/font><\/li><li><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\">Las personas con un grado de discapacidad del 100% y 1 acompa\u00f1ante tienen entrada gratuita.<\/font><\/font><\/li><li><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\">Los titulares de la Vienna City Card reciben un 16 % de descuento sobre el precio de la entrada.<\/font><\/font><\/li><\/ul><h3 id=\"t-1669899315262\" class=\"\"><strong><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\">Cupones:<\/font><\/font><\/strong><\/h3><p><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\">Tambi\u00e9n hay disponibles varios vales para el zool\u00f3gico. <\/font><font style=\"vertical-align: inherit;\">Todos los vales se pueden encontrar <\/font><\/font><a href=\"https:\/\/www.zoovienna.at\/shop\/kategorie\/Gutscheine\/\" rel=\"noopener\" target=\"_blank\"><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\">aqu\u00ed<\/font><\/font><\/a><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\"> .<\/font><\/font><\/p><h2 id=\"t-1669899315263\" class=\"\" style=\"\" data-css=\"tve-u-188b9e1b5ef\"><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\">Lugares de inter\u00e9s en el Tiergarten<\/font><\/font><\/h2><ul class=\"\"><li><strong><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\">Tirolerhof:<\/font><\/font><\/strong><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\"> disfrute del estilo tirol\u00e9s en Tirolerhof, una granja t\u00edpica de Unterinntal de 1722. <\/font><font style=\"vertical-align: inherit;\">Comprado en el zool\u00f3gico de Sch\u00f6nbrunn para salvarlo de la decadencia, removido y reconstruido aqu\u00ed pieza por pieza, el Tirolerhof presenta razas de animales dom\u00e9sticos en peligro de extinci\u00f3n en sus establos.<\/font><\/font><\/li><li><strong><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\">Pabell\u00f3n Imperial:<\/font><\/font><\/strong><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\"> En el coraz\u00f3n del Tiergarten se encuentra el Pabell\u00f3n Imperial, que una vez sirvi\u00f3 a la pareja imperial, el Emperador Francisco I y Mar\u00eda Teresa, como desayuno y sal\u00f3n social. <\/font><font style=\"vertical-align: inherit;\">Hoy es un caf\u00e9-restaurante que a\u00fan emana un estilo imperial con sus grandiosos frescos en el techo, pinturas al \u00f3leo y espejos. <\/font><font style=\"vertical-align: inherit;\">M\u00e1s sobre esto <\/font><\/font><a href=\"https:\/\/zoovienna-gastro.at\/unsere-betriebe\" rel=\"noopener\" target=\"_blank\"><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\">aqu\u00ed<\/font><\/font><\/a><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\"> .<\/font><\/font><\/li><li><strong><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\">Casa de las Palmeras:<\/font><\/font><\/strong><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\"> La Casa de las Palmeras de 1882 es una de las m\u00e1s grandes de su tipo en el mundo. <\/font><font style=\"vertical-align: inherit;\">Aqu\u00ed, los amantes de las plantas mediterr\u00e1neas, tropicales y subtropicales pueden maravillarse con diferentes tipos de plantas de tres zonas clim\u00e1ticas en tres pabellones. <\/font><font style=\"vertical-align: inherit;\">Los precios de las entradas y los horarios de apertura se pueden encontrar <\/font><\/font><a href=\"https:\/\/www.bundesgaerten.at\/schlosspark-schoenbrunn\/das-grosse-palmenhaus.html\" rel=\"noopener\" target=\"_blank\"><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\">aqu\u00ed<\/font><\/font><\/a><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\"> .<\/font><\/font><\/li><li><strong><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\">Casa del desierto:<\/font><\/font><\/strong><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\"> La casa del desierto justo enfrente de la <\/font><\/font><a href=\"http:\/\/viennatouristinformation.com\/es\/sehenswuerdigkeiten\/attraktionen\/\"><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\">casa de las palmeras<\/font><\/font><\/a><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\"> ofrece una experiencia en el desierto . <\/font><font style=\"vertical-align: inherit;\">La antigua casa del reloj de sol lleva a sus visitantes por un sendero de aventuras a trav\u00e9s de aut\u00e9nticos paisajes des\u00e9rticos desde Am\u00e9rica Central hasta Madagascar. <\/font><font style=\"vertical-align: inherit;\">Los precios de las entradas y los horarios de apertura se pueden encontrar <\/font><\/font><a href=\"https:\/\/www.zoovienna.at\/anlagen\/wuestenhaus\/\" rel=\"noopener\" target=\"_blank\"><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\">aqu\u00ed<\/font><\/font><\/a><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\"> .<\/font><\/font><\/li><\/ul><h2 id=\"t-1669899315264\" class=\"\" style=\"\" data-css=\"tve-u-188b9e1c495\"><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\">Accesos, parking y transporte p\u00fablico<\/font><\/font><\/h2><\/div><div class=\"thrv_wrapper tve_image_caption\" data-css=\"tve-u-184cdcbf9c8\"><span class=\"tve_image_frame\"><img decoding=\"async\" class=\"tve_image wp-image-1958 pin-process\" alt=\"Giraffe mit BlickEing\u00e4nge, Parken und \u00d6ffentlicher Verkehr\" data-id=\"1958\" width=\"885\" data-init-width=\"1000\" height=\"590\" data-init-height=\"667\" title=\"Eing\u00e4nge, Parken und \u00d6ffentlicher Verkehr\" loading=\"lazy\" src=\"\/\/viennatouristinformation.com\/es\/wp-content\/uploads\/2020\/09\/Eing\u00e4nge-Parken-und-\u00d6ffentlicher-Verkehr.jpg\" data-width=\"885\" data-height=\"590\" data-pin-media=\"http:\/\/viennatouristinformation.com\/es\/wp-content\/uploads\/2021\/01\/wien_pinterest_tiergarten-2.jpg\" data-pin-description=\"Zool\u00f3gico de Sch\u00f6nbrunn Viena: animales, visitas y consejos de viaje\" data-pin-url=\"https:\/\/viennatouristinformation.com\/es\/cosas-que-hacer\/atracciones\/zoologico-de-schoenbrunn\/?tve=true&amp;tcbf=d5716ea3f9\" data-pinpro-key=\"zkcltt2hw\" style=\"aspect-ratio: auto 1000 \/ 667;\"><\/span><\/div><div class=\"thrv_wrapper thrv_text_element\"><h3 id=\"t-1669899315265\" class=\"\"><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\">Entradas:<\/font><\/font><\/h3><ul class=\"\"><li><p><strong><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\">Entrada principal de Hietzing:<\/font><\/font><\/strong><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\"> puede llegar a la entrada principal del zool\u00f3gico de Sch\u00f6nbrunn a trav\u00e9s de Hietzinger Tor. <\/font><font style=\"vertical-align: inherit;\">La parada m\u00e1s cercana es la estaci\u00f3n de metro Hietzing.<\/font><\/font><\/p><\/li><li><p><strong><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\">Entrada Tirolerhof:<\/font><\/font><\/strong><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\"> Esta entrada est\u00e1 en Seckendorff-Gudent-Weg. <\/font><font style=\"vertical-align: inherit;\">Si llegas en coche y aparcas en el parking p\u00fablico, esta es la entrada m\u00e1s cercana.<\/font><\/font><\/p><\/li><li><strong><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\">Entrada Neptun:<\/font><\/font><\/strong><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\"> Esta entrada se encuentra en el <\/font><\/font><a href=\"http:\/\/viennatouristinformation.com\/es\/sehenswuerdigkeiten\/schonbrunn\/\"><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\">Parque del Palacio de Sch\u00f6nbrunn<\/font><\/font><\/a><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\"> . <\/font><font style=\"vertical-align: inherit;\">Se encuentra en el lado del castillo junto a la fuente de Neptuno.<\/font><\/font><\/li><\/ul><h3 id=\"t-1669899315266\" class=\"\"><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\">El parque:<\/font><\/font><\/h3><ul class=\"\"><li><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\">Un aparcamiento p\u00fablico est\u00e1 disponible para los visitantes del zool\u00f3gico en Seckendorff-Gudent-Weg. <\/font><font style=\"vertical-align: inherit;\">El acceso es a trav\u00e9s de Elisabeth-Allee. <\/font><font style=\"vertical-align: inherit;\">Los espacios de estacionamiento son limitados. <\/font><font style=\"vertical-align: inherit;\">Direcci\u00f3n: Seckendorff-Gudent-Weg, 1130 Viena.<\/font><\/font><\/li><li><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\">Tambi\u00e9n hay <\/font><font style=\"vertical-align: inherit;\">un aparcamiento de pago APCOA con 160 plazas en el Palacio de <\/font><\/font><a href=\"http:\/\/viennatouristinformation.com\/es\/sehenswuerdigkeiten\/schonbrunn\/\"><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\">Sch\u00f6nbrunn . <\/font><\/font><\/a><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\">Desde aqu\u00ed puede llegar al Tiergarten en unos 22 minutos a pie. <\/font><font style=\"vertical-align: inherit;\">Direcci\u00f3n: Sch\u00f6nbrunner Schlo\u00dfstrasse 50, 1130 Viena.<\/font><\/font><\/li><\/ul><h3 id=\"t-1669899315267\" class=\"\"><font style=\"vertical-align: inherit;\"><strong><font style=\"vertical-align: inherit;\">Transporte<\/font><\/strong><font style=\"vertical-align: inherit;\"> p\u00fablico :<\/font><\/font><strong><font style=\"vertical-align: inherit;\"><\/font><\/strong><\/h3><ul class=\"\"><li><strong><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\">U-Bahn:<\/font><\/font><\/strong><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\"> U4 Hietzing<\/font><\/font><\/li><li><strong><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\">Tranv\u00eda:<\/font><\/font><\/strong><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\"> 10, 58, 60 Hietzing U (Puente Kennedy)<\/font><\/font><\/li><li><strong><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\">Autobuses:<\/font><\/font><\/strong><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\"> 51A, 56A, 56B, 58A<\/font><\/font><\/li><\/ul><h2 id=\"t-1669899315268\" class=\"\" style=\"\" data-css=\"tve-u-188b9e1d86e\"><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\">Comer en el zool\u00f3gico<\/font><\/font><\/h2><\/div><div class=\"thrv_wrapper tve_image_caption\" data-css=\"tve-u-184cdcc4eb5\"><span class=\"tve_image_frame\"><img decoding=\"async\" class=\"tve_image wp-image-1959 pin-process\" alt=\"Essen im Tiergarten\" data-id=\"1959\" width=\"885\" data-init-width=\"1000\" height=\"590\" data-init-height=\"667\" title=\"Essen im Tiergarten\" loading=\"lazy\" src=\"\/\/viennatouristinformation.com\/es\/wp-content\/uploads\/2020\/09\/Essen-im-Tiergarten.jpg\" data-width=\"885\" data-height=\"590\" data-pin-media=\"http:\/\/viennatouristinformation.com\/es\/wp-content\/uploads\/2021\/01\/wien_pinterest_tiergarten-2.jpg\" data-pin-description=\"Zool\u00f3gico de Sch\u00f6nbrunn Viena: animales, visitas y consejos de viaje\" data-pin-url=\"https:\/\/viennatouristinformation.com\/es\/cosas-que-hacer\/atracciones\/zoologico-de-schoenbrunn\/?tve=true&amp;tcbf=d5716ea3f9\" data-pinpro-key=\"d4wot53qr\" style=\"aspect-ratio: auto 1000 \/ 667;\"><\/span><\/div><div class=\"thrv_wrapper thrv_text_element\"><p><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\">Numerosos restaurantes y caf\u00e9s en el Tiergarten brindan bienestar f\u00edsico a los visitantes. <\/font><font style=\"vertical-align: inherit;\">Adem\u00e1s del ya mencionado Kaiserpavillon y el Caf\u00e9 Atelier Nonja, puede disfrutar de una excelente comida en el r\u00fastico Gasthaus Tirolergarten, en el Jumbo Grillgarten o en la cervecer\u00eda al aire libre.<\/font><\/font><\/p><p><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\">El Caf\u00e9 Hietzing en la entrada de Hietzing, el Landtmann's Parkcaf\u00e9 en el parque del castillo y el Eissalon Rhino Bar, donde puede disfrutar de un delicioso helado, son todos adecuados para una pausa para el caf\u00e9.<\/font><\/font><\/p><h2 id=\"t-1669899315269\" class=\"\" style=\"\" data-css=\"tve-u-188b9e1e346\"><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\">Historia del zoologico<\/font><\/font><\/h2><\/div><div class=\"thrv_wrapper tve_image_caption\" data-css=\"tve-u-184cdcc9679\"><span class=\"tve_image_frame\"><img decoding=\"async\" class=\"tve_image wp-image-1960 pin-process\" alt=\"Geschichte des Tiergarten\" data-id=\"1960\" width=\"885\" data-init-width=\"1000\" height=\"590\" data-init-height=\"667\" title=\"Geschichte des Tiergarten\" loading=\"lazy\" src=\"\/\/viennatouristinformation.com\/es\/wp-content\/uploads\/2020\/09\/Geschichte-des-Tiergarten.jpg\" data-width=\"885\" data-height=\"590\" data-pin-media=\"http:\/\/viennatouristinformation.com\/es\/wp-content\/uploads\/2021\/01\/wien_pinterest_tiergarten-2.jpg\" data-pin-description=\"Zool\u00f3gico de Sch\u00f6nbrunn Viena: animales, visitas y consejos de viaje\" data-pin-url=\"https:\/\/viennatouristinformation.com\/es\/cosas-que-hacer\/atracciones\/zoologico-de-schoenbrunn\/?tve=true&amp;tcbf=d5716ea3f9\" data-pinpro-key=\"nzwilmdtm\" style=\"aspect-ratio: auto 1000 \/ 667;\"><\/span><\/div><div class=\"thrv_wrapper thrv_text_element\"><p><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\">El zool\u00f3gico fue inaugurado en 1752 por el emperador Francisco I Esteban de Lorena, esposo de Mar\u00eda Teresa, como una colecci\u00f3n imperial en el parque de la residencia de verano de Sch\u00f6nbrunn.<\/font><\/font><\/p><p><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\">El sistema se remonta a un dise\u00f1o del arquitecto de la corte Nicolas Jadot. <\/font><font style=\"vertical-align: inherit;\">Despu\u00e9s de un a\u00f1o de construcci\u00f3n, la casa de fieras se complet\u00f3 en 1752, con animales y presentada a los visitantes. <\/font><font style=\"vertical-align: inherit;\">El centro del complejo era el pabell\u00f3n central dise\u00f1ado como sala de desayunos, hoy el Pabell\u00f3n Imperial, que solo se complet\u00f3 en 1759. <\/font><font style=\"vertical-align: inherit;\">13 recintos de animales dispuestos radialmente lo rodean.<\/font><\/font><\/p><p><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\">No fue hasta 1779 que el zool\u00f3gico, que albergaba cada vez m\u00e1s animales, se abri\u00f3 al p\u00fablico. <\/font><font style=\"vertical-align: inherit;\">Gracias a las expediciones a \u00c1frica y Am\u00e9rica organizadas por el emperador Jos\u00e9 II, cada vez llegaban m\u00e1s animales ex\u00f3ticos como elefantes y jirafas al zool\u00f3gico.<\/font><\/font><\/p><p><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\">Con el fin de la monarqu\u00eda, el zool\u00f3gico pas\u00f3 a ser propiedad de la Rep\u00fablica de Austria. <\/font><font style=\"vertical-align: inherit;\">Sin embargo, los cuellos de botella en el suministro y las deficiencias higi\u00e9nicas provocadas por la Primera Guerra Mundial hicieron que el n\u00famero de animales se redujera en casi un 85 por ciento.<\/font><\/font><\/p><p><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\">Bajo la direcci\u00f3n del bi\u00f3logo Otto Antonius, el n\u00famero de animales volvi\u00f3 a aumentar considerablemente hasta 1930. <\/font><font style=\"vertical-align: inherit;\">Tambi\u00e9n introdujo la idea de criar especies animales en peligro de extinci\u00f3n.<\/font><\/font><\/p><p><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\">Desafortunadamente, el zool\u00f3gico no se salv\u00f3 del bombardeo de la Segunda Guerra Mundial. <\/font><font style=\"vertical-align: inherit;\">Muchos de los animales residentes perdieron la vida.<\/font><\/font><\/p><p><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\">Despu\u00e9s del extenso trabajo de restauraci\u00f3n, el zool\u00f3gico se encontr\u00f3 en una situaci\u00f3n financiera desesperada. <\/font><font style=\"vertical-align: inherit;\">Solo la privatizaci\u00f3n del zool\u00f3gico, los precios de entrada m\u00e1s altos y numerosos patrocinadores aseguraron que los recintos pudieran renovarse y ampliarse.<\/font><\/font><\/p><p><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\">El Tiergarten forma parte del Patrimonio de la Humanidad de la UNESCO de <\/font><\/font><a href=\"http:\/\/viennatouristinformation.com\/es\/sehenswuerdigkeiten\/schonbrunn\/\"><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\">Sch\u00f6nbrunn<\/font><\/font><\/a><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\"> desde 1996 .<\/font><\/font><\/p><p><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\">Incluso hoy en d\u00eda, el zool\u00f3gico en funcionamiento continuo m\u00e1s antiguo del mundo emana un estilo hist\u00f3rico. <\/font><font style=\"vertical-align: inherit;\">El Zool\u00f3gico de Sch\u00f6nbrunn es ahora el hogar de m\u00e1s de 750 especies de animales de todos los continentes y est\u00e1 dedicado a la preservaci\u00f3n y protecci\u00f3n de especies en peligro de extinci\u00f3n.<\/font><\/font><\/p><h2 id=\"t-1669899315270\" class=\"\" style=\"\" data-css=\"tve-u-188b9e1f951\"><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\">Contacto<\/font><\/font><\/h2><ul class=\"\"><li><strong><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\">Direcci\u00f3n:<\/font><\/font><\/strong><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\"> Maxingstrasse 13b, 1130 Viena<\/font><\/font><\/li><li><strong><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\">U-Bahn: &nbsp;<\/font><\/font><\/strong><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\"> U4 Hietzing<\/font><\/font><\/li><li><strong><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\">Horario de apertura:<\/font><\/font><\/strong><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\"> el zool\u00f3gico de Sch\u00f6nbrunn est\u00e1 abierto todos los d\u00edas. <\/font><font style=\"vertical-align: inherit;\">Los horarios de apertura actuales se pueden encontrar <\/font><\/font><a href=\"https:\/\/www.zoovienna.at\/besuch-und-tickets\/besucherinformation\/#oeffnungszeiten\" rel=\"noopener\" target=\"_blank\"><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\">aqu\u00ed<\/font><\/font><\/a><font style=\"vertical-align: inherit;\"><font style=\"vertical-align: inherit;\"> .<\/font><\/font><\/li><\/ul><\/div><div class=\"thrv_wrapper thrv_contentbox_shortcode thrv-content-box tve-elem-default-pad\" data-css=\"tve-u-188b9e216d0\" style=\"\">\n\t<div class=\"tve-content-box-background\"><\/div>\n\t<div class=\"tve-cb\"><div class=\"thrv_wrapper thrv_text_element\"><h3 class=\"\" style=\"\" data-css=\"tve-u-188b9e216d1\" id=\"t-1686571213368\"><strong>ART\u00cdCULOS RELACIONADOS<\/strong><\/h3><\/div>[tcb_post_list query=\"{'paged':1,'filter':'custom','post_type':|{|'page'|}|,'related':|{||}|,'orderby':'date','order':'ASC','posts_per_page':'4','offset':'1','no_posts_text':'There are no posts to display.','exclude_current_post':|{||}|,'queried_object':{'ID':917,'post_author':'3'},'dynamic_filter':{'category':'category','tag':'tag','author':'author','search':'search'},'sticky':|{||}|,'rules':|{|{'taxonomy':'page','terms':|{|'913','1257','827','822'|}|,'operator':'IN'}|}|}\" type=\"grid\" columns-d=\"2\" columns-t=\"2\" columns-m=\"1\" vertical-space-d=\"20\" horizontal-space-d=\"20\" ct=\"post_list-43458\" ct-name=\"Image &amp; Text 09\" tcb-elem-type=\"post_list\" pagination-type=\"none\" pages_near_current=\"2\" dynamic_filter='{\"category\":\"category\",\"tag\":\"tag\",\"author\":\"author\",\"search\":\"search\"}' element-name=\"Post List\" css=\"tve-u-188b9e216d2\" horizontal-space-m=\"0\" vertical-space-m=\"15\" horizontal-space-t=\"15\" vertical-space-t=\"15\" article-tcb_hover_state_parent=\"\" total_post_count=\"4\" total_sticky_count=\"0\" posts_per_page=\"4\" featured-content=\"0\" no_posts_text=\"\"  class='' ][tcb_post_list_dynamic_style]@media (min-width: 300px){[data-css=\"tve-u-188b9e216d2\"].tcb-post-list #post-[tcb_the_id] [data-css=\"tve-u-188b9e216d7\"]{background-image: url(\"[tcb_featured_image_url size=large]\") !important;}[data-css=\"tve-u-188b9e216d2\"].tcb-post-list #post-[tcb_the_id] [data-css=\"tve-u-188b9e216d6\"]:hover [data-css=\"tve-u-188b9e216d7\"]{background-image: url(\"[tcb_featured_image_url size=large]\") !important;}}[\/tcb_post_list_dynamic_style]\n<a href=\"[tcb_post_the_permalink]\" class=\"tve-dynamic-link\" dynamic-postlink=\"tcb_post_the_permalink\" data-shortcode-id=\"822\"><div class=\"thrv_wrapper thrv_contentbox_shortcode thrv-content-box tve-elem-default-pad tcb-local-vars-root\" data-css=\"tve-u-188b9e216d6\">\n\t<div class=\"tve-content-box-background\" data-css=\"tve-u-188b9e216d7\" style=\"\" data-tcb_hover_state_parent=\"1\"><\/div>\n\t<div class=\"tve-cb\" data-css=\"tve-u-188b9e216d8\"><\/div>\n<\/div><\/a>\n\n\n\t\n\n\n<div class=\"thrv_wrapper thrv_contentbox_shortcode thrv-content-box tve-elem-default-pad\" data-css=\"tve-u-188b9e216d3\">\n\t<div class=\"tve-content-box-background\" data-css=\"tve-u-188b9e216d4\"><\/div>\n\t<div class=\"tve-cb\"><div class=\"thrv_wrapper thrv_text_element\" style=\"padding-top: 0px !important; margin-top: 0px !important;\" data-css=\"tve-u-188b9e216d9\"><h2 class=\"\" data-css=\"tve-u-188b9e216da\" style=\"padding-top: 0px !important; margin-top: 0px !important; text-align: center;\" id=\"t-1686745641878\" data-hide=\"true\"><span class=\"thrive-shortcode-content\" data-shortcode=\"tcb_post_title\" data-shortcode-name=\"Post title\" data-extra_key=\"\" data-attr-link=\"1\" data-attr-target=\"0\" data-attr-rel=\"0\" data-option-inline=\"1\" data-attr-static-link=\"{&quot;className&quot;:&quot;&quot;,&quot;href&quot;:&quot;https:\/\/viennatouristinformation.com\/es\/cosas-que-hacer\/museo\/&quot;,&quot;title&quot;:&quot;30 Museos m\u00e1s importantes de Viena&quot;,&quot;class&quot;:&quot;&quot;}\" data-attr-css=\"\">[tcb_post_title link='1' target='0' rel='0' inline='1' static-link='{\"className\":\"\",\"href\":\"https:\/\/viennatouristinformation.com\/es\/cosas-que-hacer\/museo\/\",\"title\":\"30 Museos m\u00e1s importantes de Viena\",\"class\":\"\"}' css='']<\/span><\/h2><\/div><\/div>\n<\/div>\n\n\n\n\n\t\n\n[\/tcb_post_list]<\/div>\n<\/div>","tve_custom_css":"@media (min-width: 300px){[data-css=\"tve-u-184cdc5e7fc\"] { --tve-toc-indent: 15px; max-width: 900px; float: none; margin-left: auto !important; margin-right: auto !important; --tcb-local-color-4b31d: var(--tcb-skin-color-0) !important; --tcb-local-color-5fb35: rgb(64,59,59) !important; --tve-applied-max-width: 900px !important; margin-bottom: 40px !important; }[data-css=\"tve-u-184cdc5e7fe\"] { border: 1px solid rgb(221, 221, 221) !important; background-color: rgb(255, 255, 255) !important; }[data-css=\"tve-u-184cdc5e801\"] { margin-top: 0px !important; padding: 20px 30px !important; margin-bottom: 0px !important; }[data-css=\"tve-u-184cdc5e7ff\"] { padding: 30px !important; margin: 0px !important; border-bottom: 1px solid rgb(221, 221, 221) !important; }[data-css=\"tve-u-184cdc5e7ff\"] .tve-toc-title-icon { font-size: 18px !important; width: 18px !important; height: 18px !important; color: var(--tcb-local-color-4b31d) !important; --tve-applied-color: var$(--tcb-local-color-4b31d) !important; }[data-css=\"tve-u-184cdc5e803\"] { --tve-font-size: 16px; font-size: var(--tve-font-size,16px); font-weight: var(--tve-font-weight,var(--g-regular-weight,normal)); --tve-font-weight: var(--g-regular-weight,normal); font-family: var(--tve-font-family,inherit); --tve-font-family: inherit; color: var(--tve-color,var(--tcb-local-color-5fb35)); --tve-color: var(--tcb-local-color-5fb35); --tcb-applied-color: var$(--tcb-local-color-5fb35); border: none; text-decoration: var(--tve-text-decoration,none); --tve-text-decoration: none; line-height: var(--tve-line-height,1.4em); --tve-line-height: 1.4em; --tve-applied-color: var$(--tve-color,var$(--tcb-local-color-5fb35)); --tve-applied---tve-color: var$(--tcb-local-color-5fb35); margin-top: 0px !important; padding: 10px 0px !important; margin-bottom: 0px !important; background-color: transparent !important; background-image: none !important; }:not(#tve) [data-css=\"tve-u-184cdc5e803\"]:hover { background-image: none !important; color: var(--tve-color,var(--tcb-local-color-4b31d)) !important; --tve-color: var(--tcb-local-color-4b31d) !important; --tcb-applied-color: var$(--tcb-local-color-4b31d) !important; text-decoration: var(--tve-text-decoration,none) !important; --tve-text-decoration: none !important; }[data-css=\"tve-u-184cdc5e803\"].tve-state-expanded { text-decoration: var(--tve-text-decoration,none); --tve-text-decoration: none; color: var(--tve-color,rgb(255,255,255)); --tve-color: rgb(255,255,255); --tcb-applied-color: rgb(255,255,255); background-color: var(--tcb-local-color-5fb35) !important; }[data-css=\"tve-u-184cdc5e805\"] { --tve-font-size: 16px; font-size: var(--tve-font-size,16px); font-weight: var(--tve-font-weight,var(--g-regular-weight,normal)); --tve-font-weight: var(--g-regular-weight,normal); font-family: var(--tve-font-family,inherit); --tve-font-family: inherit; color: var(--tve-color,var(--tcb-local-color-5fb35)); --tve-color: var(--tcb-local-color-5fb35); --tcb-applied-color: var$(--tcb-local-color-5fb35); text-decoration: var(--tve-text-decoration,none); --tve-text-decoration: none; line-height: var(--tve-line-height,1.4em); --tve-line-height: 1.4em; padding: 10px !important; margin-top: 0px !important; margin-bottom: 0px !important; }:not(#tve) [data-css=\"tve-u-184cdc5e805\"]:hover { text-decoration: var(--tve-text-decoration,none) !important; --tve-text-decoration: none !important; color: var(--tve-color,var(--tcb-local-color-4b31d)) !important; --tve-color: var(--tcb-local-color-4b31d) !important; --tcb-applied-color: var$(--tcb-local-color-4b31d) !important; }[data-css=\"tve-u-184cdc5e805\"].tve-state-expanded { color: var(--tve-color,rgb(255,255,255)); --tve-color: rgb(255,255,255); --tcb-applied-color: rgb(255,255,255); text-decoration: var(--tve-text-decoration,none); --tve-text-decoration: none; background-color: var(--tcb-local-color-5fb35) !important; }[data-css=\"tve-u-184cdc5e806\"] { --tve-font-size: 16px; font-size: var(--tve-font-size,16px); color: var(--tve-color,var(--tcb-local-color-5fb35)); --tve-color: var(--tcb-local-color-5fb35); --tcb-applied-color: var$(--tcb-local-color-5fb35); text-decoration: var(--tve-text-decoration,none); --tve-text-decoration: none; line-height: var(--tve-line-height,1.4em); --tve-line-height: 1.4em; padding: 10px !important; margin-top: 0px !important; margin-bottom: 0px !important; }:not(#tve) [data-css=\"tve-u-184cdc5e806\"]:hover { text-decoration: var(--tve-text-decoration,none) !important; --tve-text-decoration: none !important; color: var(--tve-color,var(--tcb-local-color-4b31d)) !important; --tve-color: var(--tcb-local-color-4b31d) !important; --tcb-applied-color: var$(--tcb-local-color-4b31d) !important; }[data-css=\"tve-u-184cdc5e806\"].tve-state-expanded { color: var(--tve-color,rgb(255,255,255)); --tve-color: rgb(255,255,255); --tcb-applied-color: rgb(255,255,255); text-decoration: var(--tve-text-decoration,none); --tve-text-decoration: none; background-color: var(--tcb-local-color-5fb35) !important; }:not(#tve) [data-css=\"tve-u-184cdc5e7ff\"]:hover [data-css=\"tve-u-1739a0a76de\"]:not(.tve-state-expanded) p, :not(#tve) [data-css=\"tve-u-184cdc5e7ff\"]:hover li, :not(#tve) [data-css=\"tve-u-184cdc5e7ff\"]:hover blockquote, :not(#tve) [data-css=\"tve-u-184cdc5e7ff\"]:hover address, :not(#tve) [data-css=\"tve-u-184cdc5e7ff\"]:hover .tcb-plain-text, :not(#tve) [data-css=\"tve-u-184cdc5e7ff\"]:hover label, :not(#tve) [data-css=\"tve-u-184cdc5e7ff\"]:hover h1, :not(#tve) [data-css=\"tve-u-184cdc5e7ff\"]:hover h2, :not(#tve) [data-css=\"tve-u-184cdc5e7ff\"]:hover h3, :not(#tve) [data-css=\"tve-u-184cdc5e7ff\"]:hover h4, :not(#tve) [data-css=\"tve-u-184cdc5e7ff\"]:hover h5, :not(#tve) [data-css=\"tve-u-184cdc5e7ff\"]:hover h6 { color: var(--tve-color,var(--tcb-local-color-5fb35)) !important; --tve-applied-color: var$(--tve-color,var$(--tcb-local-color-5fb35)) !important; --tcb-applied-color: var$(--tcb-local-color-5fb35) !important; }:not(#tve) [data-css=\"tve-u-1739a0a76de\"].tve-state-expanded p, li, blockquote, address, .tcb-plain-text, label, h1, h2, h3, h4, h5, h6 { color: var(--tve-color,var(--tcb-local-color-5fb35)); --tve-applied-color: var$(--tve-color,var$(--tcb-local-color-5fb35)); --tcb-applied-color: var$(--tcb-local-color-5fb35); }[data-css=\"tve-u-184cdc5e800\"] { line-height: 1.2em !important; }:not(#tve) [data-css=\"tve-u-184cdc5e800\"] { letter-spacing: 4px; text-transform: uppercase !important; font-size: 14px !important; }[data-css=\"tve-u-184cdc5e7ff\"].tve-state-expanded { --animation-angle: -45deg; }[data-css=\"tve-u-184cdc5e7fd\"] .tve_sep { background-image: url(\"data:image\/svg+xml,%3Csvg viewBox='0 0 8 2' xmlns='http:\/\/www.w3.org\/2000\/svg' transform='rotate(90)'%3E%3Cline x1='0' y1='1' x2='8' y2='1' stroke='rgba(0,0,0,0.24)' stroke-dasharray='2' stroke-width='1' \/%3E%3C\/svg%3E\"); --tve-applied-background-image: url(\"data:image\/svg+xml,%3Csvg viewBox='0 0 8 2' xmlns='http:\/\/www.w3.org\/2000\/svg' transform='rotate(90)'%3E%3Cline x1='0' y1='1' x2='8' y2='1' stroke='rgba(0,0,0,0.24)' stroke-dasharray='2' stroke-width='1' \/%3E%3C\/svg%3E\"); background-size: 6px 6px; background-position: center top; width: 6px !important; }:not(#tve) [data-css=\"tve-u-184cdc5e804\"] .tve-toc-disabled { color: var(--tve-color,var(--tcb-local-color-4b31d)); --tve-applied-color: var$(--tve-color,var$(--tcb-local-color-4b31d)); --tcb-applied-color: var$(--tcb-local-color-4b31d); }[data-css=\"tve-u-184cdc5e804\"] { --tve-color: var(--tcb-local-color-4b31d); --tve-applied---tve-color: var$(--tcb-local-color-4b31d); padding: 0px !important; }[data-css=\"tve-u-173dc88e09d\"] { padding: 0px !important; }[data-css=\"tve-u-173dc88e7b7\"] { padding: 0px !important; }[data-css=\"tve-u-184cdcaef78\"] { width: 100%; }[data-css=\"tve-u-184cdcb4929\"] { width: 100%; }[data-css=\"tve-u-184cdcb95c6\"] { width: 100%; }[data-css=\"tve-u-184cdcbf9c8\"] { width: 100%; }[data-css=\"tve-u-184cdcc4eb5\"] { width: 100%; }[data-css=\"tve-u-184cdcc9679\"] { width: 100%; }.tcb-post-list[data-css=\"tve-u-17067be2282\"] .post-wrapper.thrv_wrapper { width: calc((100% - 0px) \/ 1); }.tcb-post-list[data-css=\"tve-u-17067be2282\"] .post-wrapper.thrv_wrapper:nth-child(n+2) { margin-top: 15px !important; }.tcb-post-list[data-css=\"tve-u-17067be2282\"] .post-wrapper.thrv_wrapper:not(:nth-child(n+2)) { margin-top: 0px !important; }.tcb-post-list[data-css=\"tve-u-17067be2282\"] .post-wrapper.thrv_wrapper:not(:nth-child(n)) { margin-right: 0px !important; }.tcb-post-list[data-css=\"tve-u-17067be2282\"] .post-wrapper.thrv_wrapper:nth-child(n) { margin-right: 0px !important; }:not(#tve) [data-css=\"tve-u-188b9e13e8e\"] { padding-bottom: 0px !important; margin-bottom: 0px !important; }:not(#tve) [data-css=\"tve-u-188b9e1851f\"] { padding-bottom: 0px !important; margin-bottom: 0px !important; }:not(#tve) [data-css=\"tve-u-188b9e19382\"] { padding-bottom: 0px !important; margin-bottom: 0px !important; }:not(#tve) [data-css=\"tve-u-188b9e1a186\"] { padding-bottom: 0px !important; margin-bottom: 0px !important; }:not(#tve) [data-css=\"tve-u-188b9e1aa42\"] { padding-bottom: 0px !important; margin-bottom: 0px !important; }:not(#tve) [data-css=\"tve-u-188b9e1b5ef\"] { padding-bottom: 11px !important; margin-bottom: 0px !important; }:not(#tve) [data-css=\"tve-u-188b9e1c495\"] { padding-bottom: 0px !important; margin-bottom: 0px !important; }:not(#tve) [data-css=\"tve-u-188b9e1d86e\"] { padding-bottom: 0px !important; margin-bottom: 0px !important; }:not(#tve) [data-css=\"tve-u-188b9e1e346\"] { padding-bottom: 0px !important; margin-bottom: 0px !important; }:not(#tve) [data-css=\"tve-u-188b9e1f951\"] { padding-bottom: 0px !important; margin-bottom: 0px !important; }[data-css=\"tve-u-188b9e216d0\"] { padding: 0px !important; margin-bottom: 0px !important; margin-top: 40px !important; }:not(#tve) [data-css=\"tve-u-188b9e216d1\"] { padding-bottom: 0px !important; margin-bottom: 0px !important; }.tcb-post-list[data-css=\"tve-u-188b9e216d2\"] .post-wrapper.thrv_wrapper { width: calc((100% - 20px) \/ 2); }[data-css=\"tve-u-188b9e216d2\"].tcb-post-list .post-wrapper { padding: 0px 0px 25px !important; background-color: rgb(255, 255, 255) !important; }[data-css=\"tve-u-188b9e216d2\"] { background-color: transparent !important; padding: 0px !important; margin-top: 10px !important; margin-bottom: 0px !important; }[data-css=\"tve-u-188b9e216d2\"].tcb-post-list [data-css=\"tve-u-188b9e216d3\"] { float: none; max-width: 85%; margin: -40px auto 0px !important; padding: 15px !important; z-index: 8 !important; }[data-css=\"tve-u-188b9e216d2\"].tcb-post-list [data-css=\"tve-u-188b9e216d4\"] { background-color: rgb(255, 255, 255) !important; }:not(#tve) [data-css=\"tve-u-188b9e216d2\"].tcb-post-list .post-wrapper:hover { background-image: none !important; --tve-applied-background-image: none !important; }[data-css=\"tve-u-188b9e216d2\"].tcb-post-list .post-wrapper::after { background-color: rgb(255, 255, 255); background-image: none !important; }[data-css=\"tve-u-188b9e216d2\"].tcb-post-list [data-css=\"tve-u-188b9e216d6\"] { margin-top: 0px !important; margin-bottom: 0px !important; z-index: 6 !important; }[data-css=\"tve-u-188b9e216d2\"].tcb-post-list [data-css=\"tve-u-188b9e216d7\"] { background-image: url(\"[tcb_featured_image_url size=large]\") !important; background-size: cover !important; background-position: 50% 50% !important; background-attachment: scroll !important; background-repeat: no-repeat !important; --background-image: url(\"[tcb_featured_image_url size=large]\") !important; --background-size: cover !important; --background-position: 50% 50% !important; --background-attachment: scroll !important; --background-repeat: no-repeat !important; --tve-applied-background-image: url(\"[tcb_featured_image_url size=large]\") !important; }[data-css=\"tve-u-188b9e216d2\"].tcb-post-list .thrv-content-box [data-css=\"tve-u-188b9e216d8\"] { min-height: 165px !important; }[data-css=\"tve-u-188b9e216d2\"].tcb-post-list [data-css=\"tve-u-188b9e216d9\"] { padding: 0px !important; margin-bottom: 15px !important; }:not(#tve) [data-css=\"tve-u-188b9e216d2\"].tcb-post-list [data-css=\"tve-u-188b9e216da\"] { padding-top: 0px !important; margin-top: 0px !important; padding-bottom: 0px !important; margin-bottom: 0px !important; font-size: 20px !important; font-weight: var(--g-bold-weight,bold) !important; }[data-css=\"tve-u-188b9e216d2\"].tcb-post-list [data-css=\"tve-u-188b9e216d6\"]:hover [data-css=\"tve-u-188b9e216d7\"] { background-image: url(\"[tcb_featured_image_url size=large]\") !important; background-size: cover !important; background-position: 50% 50% !important; background-attachment: scroll !important; background-repeat: no-repeat !important; }.tcb-post-list[data-css=\"tve-u-188b9e216d2\"] .post-wrapper.thrv_wrapper:nth-child(n+3) { margin-top: 20px !important; }.tcb-post-list[data-css=\"tve-u-188b9e216d2\"] .post-wrapper.thrv_wrapper:not(:nth-child(n+3)) { margin-top: 0px !important; }.tcb-post-list[data-css=\"tve-u-188b9e216d2\"] .post-wrapper.thrv_wrapper:not(:nth-child(2n)) { margin-right: 20px !important; }.tcb-post-list[data-css=\"tve-u-188b9e216d2\"] .post-wrapper.thrv_wrapper:nth-child(2n) { margin-right: 0px !important; }}@media (max-width: 1023px){.tcb-post-list[data-css=\"tve-u-188b9e216d2\"] .post-wrapper.thrv_wrapper { width: calc((100% - 15px) \/ 2); }[data-css=\"tve-u-188b9e216d2\"] { padding: 0px !important; }[data-css=\"tve-u-188b9e216d2\"].tcb-post-list .post-wrapper { padding: 0px 0px 25px !important; }[data-css=\"tve-u-188b9e216d2\"].tcb-post-list [data-css=\"tve-u-188b9e216d3\"] { float: none; margin-left: auto !important; margin-right: auto !important; }.tcb-post-list[data-css=\"tve-u-188b9e216d2\"] .post-wrapper.thrv_wrapper:nth-child(n+3) { margin-top: 15px !important; }.tcb-post-list[data-css=\"tve-u-188b9e216d2\"] .post-wrapper.thrv_wrapper:not(:nth-child(n+3)) { margin-top: 0px !important; }.tcb-post-list[data-css=\"tve-u-188b9e216d2\"] .post-wrapper.thrv_wrapper:not(:nth-child(2n)) { margin-right: 15px !important; }.tcb-post-list[data-css=\"tve-u-188b9e216d2\"] .post-wrapper.thrv_wrapper:nth-child(2n) { margin-right: 0px !important; }}@media (max-width: 767px){[data-css=\"tve-u-184cdc5e801\"] { padding: 6px 16px !important; }[data-css=\"tve-u-184cdc5e7ff\"] { padding: 16px !important; }.tcb-post-list[data-css=\"tve-u-188b9e216d2\"] .post-wrapper.thrv_wrapper { width: calc((100% - 0px) \/ 1); }[data-css=\"tve-u-188b9e216d2\"].tcb-post-list .post-wrapper { padding: 0px 0px 15px !important; }[data-css=\"tve-u-188b9e216d2\"].tcb-post-list [data-css=\"tve-u-188b9e216d3\"] { float: none; max-width: 90%; margin-left: auto !important; margin-right: auto !important; margin-top: -28px !important; }.tcb-post-list[data-css=\"tve-u-188b9e216d2\"] .post-wrapper.thrv_wrapper:nth-child(n+2) { margin-top: 15px !important; }.tcb-post-list[data-css=\"tve-u-188b9e216d2\"] .post-wrapper.thrv_wrapper:not(:nth-child(n+2)) { margin-top: 0px !important; }.tcb-post-list[data-css=\"tve-u-188b9e216d2\"] .post-wrapper.thrv_wrapper:nth-child(n) { margin-right: 0px !important; }[data-css=\"tve-u-188b9e216d2\"].tcb-post-list .thrv-content-box [data-css=\"tve-u-188b9e216d8\"] { min-height: 145px !important; }}","tve_user_custom_css":"","tve_globals":{"e":"1","font_cls":[]},"tcb2_ready":1,"tcb_editor_enabled":1,"tve_landing_page":"","_tve_header":"0","_tve_footer":"0"},"tags":[],"class_list":["post-917","page","type-page","status-publish","has-post-thumbnail","hentry","post-wrapper","thrv_wrapper"],"_links":{"self":[{"href":"https:\/\/viennatouristinformation.com\/es\/wp-json\/wp\/v2\/pages\/917","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/viennatouristinformation.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/viennatouristinformation.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/viennatouristinformation.com\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/viennatouristinformation.com\/es\/wp-json\/wp\/v2\/comments?post=917"}],"version-history":[{"count":0,"href":"https:\/\/viennatouristinformation.com\/es\/wp-json\/wp\/v2\/pages\/917\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/viennatouristinformation.com\/es\/wp-json\/wp\/v2\/pages\/138"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/viennatouristinformation.com\/es\/wp-json\/wp\/v2\/media\/1954"}],"wp:attachment":[{"href":"https:\/\/viennatouristinformation.com\/es\/wp-json\/wp\/v2\/media?parent=917"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/viennatouristinformation.com\/es\/wp-json\/wp\/v2\/tags?post=917"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}